{"id":406160,"date":"2025-01-27T17:48:31","date_gmt":"2025-01-27T17:48:31","guid":{"rendered":"https:\/\/galindoingenieria.com\/?page_id=406160"},"modified":"2025-01-27T17:49:46","modified_gmt":"2025-01-27T17:49:46","slug":"backupproyectos","status":"publish","type":"page","link":"https:\/\/galindoingenieria.com\/eng\/backupproyectos\/","title":{"rendered":"backupproyectos"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb96px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAVENIR REAL|800|||||||\u00bb text_text_color=\u00bb#0d0f7a\u00bb text_font_size=\u00bb54px\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||68px|||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p>Proyectos<\/p>\n<p>[\/et_pb_text][et_pb_text module_id=\u00bbmain\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAvenir||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb text_orientation=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>A continuaci\u00f3n, se presentan una selecci\u00f3n peque\u00f1a de nuestros proyectos que han tenido un detalle at\u00edpico, ya sea por su trascendencia arquitect\u00f3nica, una dificultad estructural o una dificultad de c\u00e1lculo.<\/span><\/p>\n<p><span style=\"text-decoration: underline;\">Haga click en la categor\u00eda que desee ver.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_6,1_6,1_6,1_6,1_6,1_6&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; make_equal=\u00bbon\u00bb disabled_on=\u00bbon|off|off\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb77%\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAVENIR REAL|700|||on|||#E09900|\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb19px\u00bb text_line_height=\u00bb1.8em\u00bb background_image=\u00bbhttp:\/\/galindoingenieria.com\/wp-content\/uploads\/2023\/04\/s1.jpg\u00bb text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb76px||300px||false|false\u00bb link_option_url=\u00bb#hormigon1&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p>Hormig\u00f3n Pretensado<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAVENIR REAL|700|||on|||#E09900|\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb19px\u00bb text_line_height=\u00bb1.8em\u00bb background_image=\u00bbhttp:\/\/galindoingenieria.com\/wp-content\/uploads\/2023\/04\/s2.jpg\u00bb text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb76px||300px||false|false\u00bb link_option_url=\u00bb#hormigon2&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p>Hormig\u00f3n\u00a0 Armado<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAVENIR REAL|700|||on|||#E09900|\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb19px\u00bb text_line_height=\u00bb1.8em\u00bb background_image=\u00bbhttp:\/\/galindoingenieria.com\/wp-content\/uploads\/2023\/04\/s3.jpg\u00bb text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb76px||300px||false|false\u00bb link_option_url=\u00bb#metalica\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p>Estructuras Met\u00e1licas<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAVENIR REAL|700|||on|||#E09900|\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb19px\u00bb text_line_height=\u00bb1.8em\u00bb background_image=\u00bbhttp:\/\/galindoingenieria.com\/wp-content\/uploads\/2023\/04\/s5.jpg\u00bb text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb76px||265px||false|false\u00bb link_option_url=\u00bb#reparacion\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>Reparaci\u00f3n de estructuras y patolog\u00eda<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAVENIR REAL|700|||on|||#E09900|\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb19px\u00bb text_line_height=\u00bb1.8em\u00bb background_image=\u00bbhttp:\/\/galindoingenieria.com\/wp-content\/uploads\/2023\/04\/s6.jpg\u00bb text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb76px||265px||false|false\u00bb link_option_url=\u00bb#programas\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>Desarrollo de Programas Estructurales<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAVENIR REAL|700|||on|||#E09900|\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb19px\u00bb text_line_height=\u00bb1.8em\u00bb background_image=\u00bbhttp:\/\/galindoingenieria.com\/wp-content\/uploads\/2023\/04\/s7.jpg\u00bb text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb76px||299px||false|false\u00bb link_option_url=\u00bb#verificacion\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>Dise\u00f1o y Verificaci\u00f3n<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=\u00bboff|off|on\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][wdcl_image_carousel is_variable_width=\u00bbon\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][wdcl_image_carousel_child photo=\u00bbhttp:\/\/galindoingenieria.com\/wp-content\/uploads\/2023\/04\/s1.jpg\u00bb title=\u00bbHormig\u00f3n Pretensado\u00bb title_bottom_spacing=\u00bb21px\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbAVENIR REAL|700|||on|||#E09900|\u00bb title_text_color=\u00bb#FFFFFF\u00bb title_font_size=\u00bb46px\u00bb link_option_url=\u00bb#hormigon1&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/wdcl_image_carousel_child][wdcl_image_carousel_child photo=\u00bbhttp:\/\/galindoingenieria.com\/wp-content\/uploads\/2023\/04\/s2.jpg\u00bb title=\u00bbHormig\u00f3n Armado\u00bb title_bottom_spacing=\u00bb21px\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbAVENIR REAL|700|||on|||#E09900|\u00bb title_text_color=\u00bb#FFFFFF\u00bb title_font_size=\u00bb46px\u00bb link_option_url=\u00bb#hormigon2&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/wdcl_image_carousel_child][wdcl_image_carousel_child photo=\u00bbhttp:\/\/galindoingenieria.com\/wp-content\/uploads\/2023\/04\/s3.jpg\u00bb title=\u00bbEstructuras Met\u00e1licas\u00bb title_bottom_spacing=\u00bb21px\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbAVENIR REAL|700|||on|||#E09900|\u00bb title_text_color=\u00bb#FFFFFF\u00bb title_font_size=\u00bb46px\u00bb link_option_url=\u00bb#metalica\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/wdcl_image_carousel_child][wdcl_image_carousel_child photo=\u00bbhttp:\/\/galindoingenieria.com\/wp-content\/uploads\/2023\/04\/s5.jpg\u00bb title=\u00bbReparaci\u00f3n de estructuras y patolog\u00eda\u00bb title_bottom_spacing=\u00bb21px\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbAVENIR REAL|700|||on|||#E09900|\u00bb title_text_color=\u00bb#FFFFFF\u00bb title_font_size=\u00bb46px\u00bb link_option_url=\u00bb#reparacion\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/wdcl_image_carousel_child][wdcl_image_carousel_child photo=\u00bbhttp:\/\/galindoingenieria.com\/wp-content\/uploads\/2023\/04\/s6.jpg\u00bb title=\u00bbDesarrollo de Programas Estructurales\u00bb title_bottom_spacing=\u00bb21px\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbAVENIR REAL|700|||on|||#E09900|\u00bb title_text_color=\u00bb#FFFFFF\u00bb title_font_size=\u00bb46px\u00bb link_option_url=\u00bb#programas\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/wdcl_image_carousel_child][wdcl_image_carousel_child photo=\u00bbhttp:\/\/galindoingenieria.com\/wp-content\/uploads\/2023\/04\/s7.jpg\u00bb title=\u00bbDise\u00f1o y Verificaci\u00f3n\u00bb title_bottom_spacing=\u00bb21px\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbAVENIR REAL|700|||on|||#E09900|\u00bb title_text_color=\u00bb#FFFFFF\u00bb title_font_size=\u00bb46px\u00bb link_option_url=\u00bb#verificacion\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/wdcl_image_carousel_child][\/wdcl_image_carousel][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px||3px|||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px||1px|||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_divider color=\u00bb#E09900&#8243; divider_position=\u00bbcenter\u00bb divider_weight=\u00bb2px\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; module_id=\u00bbhormigon1&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttp:\/\/galindoingenieria.com\/wp-content\/uploads\/2023\/04\/1.jpg\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAVENIR REAL|800|||||||\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb54px\u00bb text_orientation=\u00bbcenter\u00bb text_font_last_edited=\u00bboff|desktop\u00bb text_font_size_tablet=\u00bb54px\u00bb text_font_size_phone=\u00bb29px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p>Hormig\u00f3n Pretensado<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT|800|||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb54px\u00bb text_line_height=\u00bb1.2em\u00bb text_orientation=\u00bbcenter\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb\u00bb width_last_edited=\u00bbon|phone\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb54px\u00bb text_font_size_phone=\u00bb34px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p>Casa Grande del Pueblo<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][dondivi_gallery gallery_ids=\u00bb198,202,204,178&#8243; image_count=\u00bb3&#8243; load_more=\u00bbon\u00bb load_more_text=\u00bbCargar M\u00e1s\u00bb show_pagination=\u00bboff\u00bb image_zoom=\u00bbon\u00bb overlay=\u00bbon\u00bb on_click=\u00bblightbox\u00bb lightbox_title=\u00bboff\u00bb lightbox_caption=\u00bboff\u00bb hover_overlay_color=\u00bbrgba(28,55,101,0.71)\u00bb hover_icon=\u00bb&#x4c;||divi||400&#8243; hover_icon_color=\u00bb#f79839&#8243; hover_icon_width=\u00bb35px\u00bb effect_opacity=\u00bbon\u00bb layout_gap_tablet=\u00bb20px\u00bb layout_gap_phone=\u00bb10px\u00bb layout_gap_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbGALINDOFONT|600|||||||\u00bb title_text_color=\u00bb#FFCB58&#8243; title_font_size=\u00bb17px\u00bb caption_font=\u00bbGALINDOFONT||||||||\u00bb caption_font_size=\u00bb13px\u00bb caption_line_height=\u00bb1.3em\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#F6F1EC\u00bb button_bg_color=\u00bb#f79839&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#f4c538&#8243; button_border_radius=\u00bb50px\u00bb button_font=\u00bbGALINDOFONT||||||||\u00bb button_use_icon=\u00bboff\u00bb button_alignment=\u00bbcenter\u00bb button_custom_margin=\u00bb||||false|false\u00bb button_custom_padding=\u00bb7px|37px|7px|37px|true|true\u00bb image_icon_custom_margin=\u00bb||0px||false|false\u00bb image_icon_custom_padding=\u00bb||0px||false|false\u00bb filter_custom_padding_tablet=\u00bb||10px||false|false\u00bb filter_custom_padding_phone=\u00bb|5px|10px|5px|false|true\u00bb filter_custom_padding_last_edited=\u00bbon|phone\u00bb max_width=\u00bb709px\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|desktop\u00bb module_alignment=\u00bbcenter\u00bb animation_style=\u00bbfade\u00bb animation_duration=\u00bb500ms\u00bb title_font_size_tablet=\u00bb\u00bb title_font_size_phone=\u00bb18px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb caption_text_align_phone=\u00bbcenter\u00bb caption_text_align_last_edited=\u00bboff|phone\u00bb caption_font_size_tablet=\u00bb15px\u00bb caption_font_size_phone=\u00bb13px\u00bb caption_font_size_last_edited=\u00bbon|phone\u00bb filter_font_size_tablet=\u00bb20px\u00bb filter_font_size_phone=\u00bb17px\u00bb filter_font_size_last_edited=\u00bbon|phone\u00bb border_radii_image=\u00bbon|10px|10px|10px|10px\u00bb border_color_all_image=\u00bbRGBA(255,255,255,0)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb filter_text_color__hover_enabled=\u00bbon|hover\u00bb filter_text_color__hover=\u00bb#764699&#8243; border_color_all_image__hover_enabled=\u00bbon|desktop\u00bb border_color_all_image__hover=\u00bb#F6F1EC\u00bb button_border_color__hover_enabled=\u00bbon|desktop\u00bb button_border_color__hover=\u00bb#f2b437&#8243; button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#F6F1EC\u00bb button_bg_color__hover_enabled=\u00bbon|desktop\u00bb button_bg_color__hover=\u00bb#ffb73a\u00bb button_bg_enable_color__hover=\u00bbon\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/dondivi_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text module_class=\u00bbpa-toggle-text\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\" style=\"text-align: left;\">Es uno de los edificios m\u00e1s altos del pa\u00eds contando con 130 metros de altura. Se trata del edificio del poder ejecutivo, ubicado en la calle Potos\u00ed esquina Bolivar, interconectado con el Palacio de Gobierno hist\u00f3rico de la <a tabindex=\"-1\"><\/a>plaza Murillo, en la ciudad de La Paz &#8211; Bolivia.<\/div>\n<div dir=\"auto\" style=\"text-align: left;\">\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: left;\">\n<div dir=\"auto\">\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: left;\">\n<div dir=\"auto\"><\/div>\n<\/div>\n<p style=\"text-align: left;\">\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: left;\">\n<div dir=\"auto\">\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: left;\">\n<div dir=\"auto\">\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: left;\">\n<div dir=\"auto\">\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: left;\">\n<div dir=\"auto\"><\/div>\n<\/div>\n<p style=\"text-align: left;\">\n<\/div>\n<\/div>\n<p>Una de sus principales caracter\u00edsticas estructurales es que tiene un auditorio con un aforo aproximado de 1,100 personas, mismo que contempla un voladizo de 11 metros hacia la calle Potos\u00ed.<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: left;\">\n<div dir=\"auto\">\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: left;\">\n<div dir=\"auto\">\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: left;\">\n<div dir=\"auto\">\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: left;\">\n<div dir=\"auto\"><\/div>\n<\/div>\n<p style=\"text-align: left;\">\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div dir=\"auto\">\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: left;\">\n<div dir=\"auto\">\n<p>El problema estructural es que el voladizo provoca un momento de vuelco importante sobre el edificio que, en condiciones normales, inclinar\u00eda al edificio. Por ello, fue necesario dise\u00f1ar un sistema interno autoequilibrante para compensar ese momento de vuelco. De esta forma, la verdadera soluci\u00f3n estructural no est\u00e1 en el voladizo mismo, sino en el interior del edificio. Es interesante notar que tanto el voladizo como el sistema interno autoequilibrante fueron dise\u00f1ados en hormig\u00f3n postesado.<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: left;\">\n<div dir=\"auto\">\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: left;\">\n<div dir=\"auto\"><\/div>\n<\/div>\n<p style=\"text-align: left;\">\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: left;\">\n<div dir=\"auto\">\n<p>La Casa Grande del Pueblo cuenta con 29 plantas y un helipuerto. Tiene 29,492 metros cuadrados construidos. Varios pisos, entre ellos el auditorio, tienen una carga de servicio de 1,000 kg\/m2. La altura media piso-piso es de 4.5 metros. Su dise\u00f1o, por ser el principal edificio gubernamental, tiene una capacidad sismorresistente muy elevada.<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: left;\">\n<div dir=\"auto\"><\/div>\n<\/div>\n<p style=\"text-align: left;\">\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: left;\">\n<div dir=\"auto\">Nuestro trabajo consisti\u00f3 en el c\u00e1lculo y dise\u00f1o estructural, as\u00ed como la supervisi\u00f3n de la obra gruesa que estuvo a cargo de nuestro PhD. MSc. Ing. Mario Galindo Queralt.<\/div>\n<\/div>\n<p style=\"text-align: left;\"><span><\/span><\/p>\n<p style=\"text-align: left;\"><span><\/span><\/p>\n<ul>\n<li style=\"text-align: left;\"><span>Fecha: 2018 \u2013 La Paz, Bolivia<\/span><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_button button_text=\u00bbDis\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb17px||21px|||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_divider color=\u00bb#E09900&#8243; divider_weight=\u00bb4px\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT|800|||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb54px\u00bb text_line_height=\u00bb1.2em\u00bb text_orientation=\u00bbcenter\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb\u00bb width_last_edited=\u00bbon|phone\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb54px\u00bb text_font_size_phone=\u00bb34px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p>Banco de Cr\u00e9dito<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][dondivi_gallery gallery_ids=\u00bb267,405622,280,279,204,405621,405623&#8243; image_count=\u00bb3&#8243; load_more=\u00bbon\u00bb load_more_text=\u00bbCargar M\u00e1s\u00bb show_pagination=\u00bboff\u00bb image_zoom=\u00bbon\u00bb overlay=\u00bbon\u00bb on_click=\u00bblightbox\u00bb lightbox_title=\u00bboff\u00bb lightbox_caption=\u00bboff\u00bb hover_overlay_color=\u00bbrgba(28,55,101,0.71)\u00bb hover_icon=\u00bb&#x4c;||divi||400&#8243; hover_icon_color=\u00bb#f79839&#8243; hover_icon_width=\u00bb35px\u00bb effect_opacity=\u00bbon\u00bb layout_columns_tablet=\u00bb\u00bb layout_columns_phone=\u00bb2&#8243; layout_columns_last_edited=\u00bbon|desktop\u00bb layout_gap_tablet=\u00bb20px\u00bb layout_gap_phone=\u00bb10px\u00bb layout_gap_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbGALINDOFONT|600|||||||\u00bb title_text_color=\u00bb#FFCB58&#8243; title_font_size=\u00bb17px\u00bb caption_font=\u00bbGALINDOFONT||||||||\u00bb caption_font_size=\u00bb13px\u00bb caption_line_height=\u00bb1.3em\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#F6F1EC\u00bb button_bg_color=\u00bb#f79839&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#f4c538&#8243; button_border_radius=\u00bb50px\u00bb button_font=\u00bbGALINDOFONT||||||||\u00bb button_use_icon=\u00bboff\u00bb button_alignment=\u00bbcenter\u00bb button_custom_margin=\u00bb||||false|false\u00bb button_custom_padding=\u00bb7px|37px|7px|37px|true|true\u00bb image_icon_custom_margin=\u00bb||0px||false|false\u00bb image_icon_custom_padding=\u00bb||0px||false|false\u00bb filter_custom_padding_tablet=\u00bb||10px||false|false\u00bb filter_custom_padding_phone=\u00bb|5px|10px|5px|false|true\u00bb filter_custom_padding_last_edited=\u00bbon|phone\u00bb max_width=\u00bb709px\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|desktop\u00bb module_alignment=\u00bbcenter\u00bb custom_padding=\u00bb||0px|||\u00bb animation_style=\u00bbfade\u00bb animation_duration=\u00bb500ms\u00bb title_font_size_tablet=\u00bb\u00bb title_font_size_phone=\u00bb18px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb caption_text_align_phone=\u00bbcenter\u00bb caption_text_align_last_edited=\u00bboff|phone\u00bb caption_font_size_tablet=\u00bb15px\u00bb caption_font_size_phone=\u00bb13px\u00bb caption_font_size_last_edited=\u00bbon|phone\u00bb filter_font_size_tablet=\u00bb20px\u00bb filter_font_size_phone=\u00bb17px\u00bb filter_font_size_last_edited=\u00bbon|phone\u00bb border_radii_image=\u00bbon|10px|10px|10px|10px\u00bb border_color_all_image=\u00bbRGBA(255,255,255,0)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb filter_text_color__hover_enabled=\u00bbon|hover\u00bb filter_text_color__hover=\u00bb#764699&#8243; border_color_all_image__hover_enabled=\u00bbon|desktop\u00bb border_color_all_image__hover=\u00bb#F6F1EC\u00bb button_border_color__hover_enabled=\u00bbon|desktop\u00bb button_border_color__hover=\u00bb#f2b437&#8243; button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#F6F1EC\u00bb button_bg_color__hover_enabled=\u00bbon|desktop\u00bb button_bg_color__hover=\u00bb#ffb73a\u00bb button_bg_enable_color__hover=\u00bbon\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/dondivi_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text module_class=\u00bbpa-toggle-text\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Se trata de un edificio de oficinas ubicado en Obrajes de la ciudad de La Paz.<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p><span><a tabindex=\"-1\"><\/a><\/span>Cuenta con una arquitectura llamativa que consiste en ventanas transparentes para mostrar la estructura. La principal caracter\u00edstica estructural es que est\u00e1 hecho con losas de 15 cent\u00edmetros de espesor de hormig\u00f3n postesado, con luces de 9 metros entre apoyos y voladizos de 2 metros en fachada.<\/p>\n<p>El edificio tiene 14 plantas y una superficie construida de 8,500 [m2].<\/p>\n<p>Nuestro trabajo consisti\u00f3 en el c\u00e1lculo, la optimizaci\u00f3n y el dise\u00f1o estructural; as\u00ed como la supervisi\u00f3n de la construcci\u00f3n. Todo estuvo a cargo de nuestro PhD. MSc. Ing. Mario Galindo Queralt.<\/p>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<ul>\n<li><span>Fecha: 2004 \u2013 La Paz, Bolivia.<\/span><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb17px||21px|||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_divider color=\u00bb#E09900&#8243; divider_weight=\u00bb4px\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT|800|||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb54px\u00bb text_line_height=\u00bb1.2em\u00bb text_orientation=\u00bbcenter\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb\u00bb width_last_edited=\u00bbon|phone\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb54px\u00bb text_font_size_phone=\u00bb34px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p>Piscina Ol\u00edmpica<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][dondivi_gallery gallery_ids=\u00bb405615,405616,405617,405618,165,664,284,268,283&#8243; image_count=\u00bb3&#8243; load_more=\u00bbon\u00bb load_more_text=\u00bbCargar M\u00e1s\u00bb show_pagination=\u00bboff\u00bb image_zoom=\u00bbon\u00bb overlay=\u00bbon\u00bb on_click=\u00bblightbox\u00bb lightbox_title=\u00bboff\u00bb lightbox_caption=\u00bboff\u00bb layout=\u00bbgrid\u00bb hover_overlay_color=\u00bbrgba(28,55,101,0.71)\u00bb hover_icon=\u00bb&#x4c;||divi||400&#8243; hover_icon_color=\u00bb#f79839&#8243; hover_icon_width=\u00bb35px\u00bb effect_opacity=\u00bbon\u00bb layout_columns_tablet=\u00bb\u00bb layout_columns_phone=\u00bb2&#8243; layout_columns_last_edited=\u00bbon|desktop\u00bb layout_gap_tablet=\u00bb20px\u00bb layout_gap_phone=\u00bb10px\u00bb layout_gap_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbGALINDOFONT|600|||||||\u00bb title_text_color=\u00bb#FFCB58&#8243; title_font_size=\u00bb17px\u00bb caption_font=\u00bbGALINDOFONT||||||||\u00bb caption_font_size=\u00bb13px\u00bb caption_line_height=\u00bb1.3em\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#F6F1EC\u00bb button_bg_color=\u00bb#f79839&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#f4c538&#8243; button_border_radius=\u00bb50px\u00bb button_font=\u00bbGALINDOFONT||||||||\u00bb button_use_icon=\u00bboff\u00bb button_alignment=\u00bbcenter\u00bb button_custom_margin=\u00bb||||false|false\u00bb button_custom_padding=\u00bb7px|37px|7px|37px|true|true\u00bb image_icon_custom_margin=\u00bb||0px||false|false\u00bb image_icon_custom_padding=\u00bb||0px||false|false\u00bb filter_custom_padding_tablet=\u00bb||10px||false|false\u00bb filter_custom_padding_phone=\u00bb|5px|10px|5px|false|true\u00bb filter_custom_padding_last_edited=\u00bbon|phone\u00bb max_width=\u00bb709px\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|desktop\u00bb module_alignment=\u00bbcenter\u00bb animation_style=\u00bbfade\u00bb animation_duration=\u00bb500ms\u00bb title_font_size_tablet=\u00bb\u00bb title_font_size_phone=\u00bb18px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb caption_text_align_phone=\u00bbcenter\u00bb caption_text_align_last_edited=\u00bboff|phone\u00bb caption_font_size_tablet=\u00bb15px\u00bb caption_font_size_phone=\u00bb13px\u00bb caption_font_size_last_edited=\u00bbon|phone\u00bb filter_font_size_tablet=\u00bb20px\u00bb filter_font_size_phone=\u00bb17px\u00bb filter_font_size_last_edited=\u00bbon|phone\u00bb border_radii_image=\u00bbon|10px|10px|10px|10px\u00bb border_color_all_image=\u00bbRGBA(255,255,255,0)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb filter_text_color__hover_enabled=\u00bbon|hover\u00bb filter_text_color__hover=\u00bb#764699&#8243; border_color_all_image__hover_enabled=\u00bbon|desktop\u00bb border_color_all_image__hover=\u00bb#F6F1EC\u00bb button_border_color__hover_enabled=\u00bbon|desktop\u00bb button_border_color__hover=\u00bb#f2b437&#8243; button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#F6F1EC\u00bb button_bg_color__hover_enabled=\u00bbon|desktop\u00bb button_bg_color__hover=\u00bb#ffb73a\u00bb button_bg_enable_color__hover=\u00bbon\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/dondivi_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text module_class=\u00bbpa-toggle-text\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<div dir=\"auto\">Una estructura para albergar dos piscinas ol\u00edmpicas, la primera de 50 metros de largo, 25 metros de ancho y 2 metros de profundidad y la segunda de 25 metros por 25 metros y 5 metros de profundidad. La principal caracter\u00edstica es su techo que est\u00e1 conformado por una membrana postensada en hiperboloide parab\u00f3lico sujeta por dos arcos hiperb\u00f3licos de 120 metros de longitud y 60 metros de altura para cubrir una superficie de 5,400 [m2].<\/div>\n<div dir=\"auto\">\n<p>&nbsp;<\/p>\n<\/div>\n<div dir=\"auto\">Arquitectura, dise\u00f1o, <span><a tabindex=\"-1\"><\/a><\/span>c\u00e1lculo y contrucci\u00f3n realizado por el Ing. Mario Galindo Rojas.<\/div>\n<p>&nbsp;<\/p>\n<ul>\n<li><span>Fecha: 1977 \u2013 La Paz, Bolivia.<\/span><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; module_id=\u00bbhormigon2&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttp:\/\/galindoingenieria.com\/wp-content\/uploads\/2023\/04\/2.jpg\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row module_id=\u00bbHormigon2&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAVENIR REAL|800|||||||\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb54px\u00bb text_orientation=\u00bbcenter\u00bb text_font_last_edited=\u00bboff|desktop\u00bb text_font_size_tablet=\u00bb\u00bb text_font_size_phone=\u00bb29px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p>Hormig\u00f3n Armado<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT|800|||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb54px\u00bb text_line_height=\u00bb1.2em\u00bb text_orientation=\u00bbcenter\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb\u00bb width_last_edited=\u00bbon|phone\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb54px\u00bb text_font_size_phone=\u00bb34px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p>Iglesia de<br \/>San Miguel Arc\u00e1ngel<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][dondivi_gallery gallery_ids=\u00bb405625,405629,405626,405627,288,285,693,287,405628&#8243; image_count=\u00bb3&#8243; load_more=\u00bbon\u00bb load_more_text=\u00bbCargar M\u00e1s\u00bb show_pagination=\u00bboff\u00bb image_zoom=\u00bbon\u00bb overlay=\u00bbon\u00bb on_click=\u00bblightbox\u00bb lightbox_title=\u00bboff\u00bb lightbox_caption=\u00bboff\u00bb hover_overlay_color=\u00bbrgba(28,55,101,0.71)\u00bb hover_icon=\u00bb&#x4c;||divi||400&#8243; hover_icon_color=\u00bb#f79839&#8243; hover_icon_width=\u00bb35px\u00bb effect_opacity=\u00bbon\u00bb layout_columns_tablet=\u00bb\u00bb layout_columns_phone=\u00bb2&#8243; layout_columns_last_edited=\u00bbon|phone\u00bb layout_gap_tablet=\u00bb20px\u00bb layout_gap_phone=\u00bb10px\u00bb layout_gap_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbGALINDOFONT|600|||||||\u00bb title_text_color=\u00bb#FFCB58&#8243; title_font_size=\u00bb17px\u00bb caption_font=\u00bbGALINDOFONT||||||||\u00bb caption_font_size=\u00bb13px\u00bb caption_line_height=\u00bb1.3em\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#F6F1EC\u00bb button_bg_color=\u00bb#f79839&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#f4c538&#8243; button_border_radius=\u00bb50px\u00bb button_font=\u00bbGALINDOFONT||||||||\u00bb button_use_icon=\u00bboff\u00bb button_alignment=\u00bbcenter\u00bb button_custom_margin=\u00bb||||false|false\u00bb button_custom_padding=\u00bb7px|37px|7px|37px|true|true\u00bb image_icon_custom_margin=\u00bb||0px||false|false\u00bb image_icon_custom_padding=\u00bb||0px||false|false\u00bb filter_custom_padding_tablet=\u00bb||10px||false|false\u00bb filter_custom_padding_phone=\u00bb|5px|10px|5px|false|true\u00bb filter_custom_padding_last_edited=\u00bbon|phone\u00bb max_width=\u00bb709px\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|desktop\u00bb module_alignment=\u00bbcenter\u00bb animation_style=\u00bbfade\u00bb animation_duration=\u00bb500ms\u00bb title_font_size_tablet=\u00bb\u00bb title_font_size_phone=\u00bb18px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb caption_text_align_phone=\u00bbcenter\u00bb caption_text_align_last_edited=\u00bboff|phone\u00bb caption_font_size_tablet=\u00bb15px\u00bb caption_font_size_phone=\u00bb13px\u00bb caption_font_size_last_edited=\u00bbon|phone\u00bb filter_font_size_tablet=\u00bb20px\u00bb filter_font_size_phone=\u00bb17px\u00bb filter_font_size_last_edited=\u00bbon|phone\u00bb border_radii_image=\u00bbon|10px|10px|10px|10px\u00bb border_color_all_image=\u00bbRGBA(255,255,255,0)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb filter_text_color__hover_enabled=\u00bbon|hover\u00bb filter_text_color__hover=\u00bb#764699&#8243; border_color_all_image__hover_enabled=\u00bbon|desktop\u00bb border_color_all_image__hover=\u00bb#F6F1EC\u00bb button_border_color__hover_enabled=\u00bbon|desktop\u00bb button_border_color__hover=\u00bb#f2b437&#8243; button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#F6F1EC\u00bb button_bg_color__hover_enabled=\u00bbon|desktop\u00bb button_bg_color__hover=\u00bb#ffb73a\u00bb button_bg_enable_color__hover=\u00bbon\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/dondivi_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text module_class=\u00bbpa-toggle-text\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>La Iglesia de San Miguel Arc\u00e1ngel es un hito urbano.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Est\u00e1 conformada por 8 cascaras de hormig\u00f3n armado con forma de coseno hiperb\u00f3lico troncoc\u00f3nico de 15 cent\u00edmetros de espesor, una altura de 20 metros y una superficie interior construida de 530 [m2].<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">La <span><a tabindex=\"-1\"><\/a><\/span>concepci\u00f3n arquitect\u00f3nica, el dise\u00f1o estructural y la construcci\u00f3n fueron realizados por el ingeniero don Mario Galindo Rojas, como tesis de grado, para obtener la licenciatura en ingenier\u00eda civil.<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Menciones honor\u00edficas:<\/div>\n<div dir=\"auto\">&#8211; El artista don Ricardo P\u00e9rez Alcal\u00e1, quien pint\u00f3 varios cuadros de la iglesia y dise\u00f1\u00f3 muchos detalles de la misma.<\/div>\n<div dir=\"auto\">&#8211; El Maestro don Florentino L\u00f3pez, quien fue el principal alba\u00f1il durante la construcci\u00f3n.<\/div>\n<div dir=\"auto\">Ambos fueron amigos entra\u00f1ables de don Mario Galindo Rojas toda su vida.<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<ul>\n<li><span>Fecha: 1967 \u2013 La Paz, Bolivia.<\/span><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb17px||21px|||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_divider color=\u00bb#E09900&#8243; divider_weight=\u00bb4px\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT|800|||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb54px\u00bb text_line_height=\u00bb1.2em\u00bb text_orientation=\u00bbcenter\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb\u00bb width_last_edited=\u00bbon|phone\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb54px\u00bb text_font_size_phone=\u00bb34px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p>Parroquia Coraz\u00f3n de Mar\u00eda<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][dondivi_gallery gallery_ids=\u00bb405632,405635,405636,405633,291,709,707,320,290&#8243; image_count=\u00bb3&#8243; load_more=\u00bbon\u00bb load_more_text=\u00bbCargar M\u00e1s\u00bb show_pagination=\u00bboff\u00bb image_zoom=\u00bbon\u00bb overlay=\u00bbon\u00bb on_click=\u00bblightbox\u00bb lightbox_title=\u00bboff\u00bb lightbox_caption=\u00bboff\u00bb hover_overlay_color=\u00bbrgba(28,55,101,0.71)\u00bb hover_icon=\u00bb&#x4c;||divi||400&#8243; hover_icon_color=\u00bb#f79839&#8243; hover_icon_width=\u00bb35px\u00bb effect_opacity=\u00bbon\u00bb layout_columns_tablet=\u00bb\u00bb layout_columns_phone=\u00bb2&#8243; layout_columns_last_edited=\u00bbon|phone\u00bb layout_gap_tablet=\u00bb20px\u00bb layout_gap_phone=\u00bb10px\u00bb layout_gap_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbGALINDOFONT|600|||||||\u00bb title_text_color=\u00bb#FFCB58&#8243; title_font_size=\u00bb17px\u00bb caption_font=\u00bbGALINDOFONT||||||||\u00bb caption_font_size=\u00bb13px\u00bb caption_line_height=\u00bb1.3em\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#F6F1EC\u00bb button_bg_color=\u00bb#f79839&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#f4c538&#8243; button_border_radius=\u00bb50px\u00bb button_font=\u00bbGALINDOFONT||||||||\u00bb button_use_icon=\u00bboff\u00bb button_alignment=\u00bbcenter\u00bb button_custom_margin=\u00bb||||false|false\u00bb button_custom_padding=\u00bb7px|37px|7px|37px|true|true\u00bb image_icon_custom_margin=\u00bb||0px||false|false\u00bb image_icon_custom_padding=\u00bb||0px||false|false\u00bb filter_custom_padding_tablet=\u00bb||10px||false|false\u00bb filter_custom_padding_phone=\u00bb|5px|10px|5px|false|true\u00bb filter_custom_padding_last_edited=\u00bbon|phone\u00bb max_width=\u00bb709px\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|desktop\u00bb module_alignment=\u00bbcenter\u00bb animation_style=\u00bbfade\u00bb animation_duration=\u00bb500ms\u00bb title_font_size_tablet=\u00bb\u00bb title_font_size_phone=\u00bb18px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb caption_text_align_phone=\u00bbcenter\u00bb caption_text_align_last_edited=\u00bboff|phone\u00bb caption_font_size_tablet=\u00bb15px\u00bb caption_font_size_phone=\u00bb13px\u00bb caption_font_size_last_edited=\u00bbon|phone\u00bb filter_font_size_tablet=\u00bb20px\u00bb filter_font_size_phone=\u00bb17px\u00bb filter_font_size_last_edited=\u00bbon|phone\u00bb border_radii_image=\u00bbon|10px|10px|10px|10px\u00bb border_color_all_image=\u00bbRGBA(255,255,255,0)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb filter_text_color__hover_enabled=\u00bbon|hover\u00bb filter_text_color__hover=\u00bb#764699&#8243; border_color_all_image__hover_enabled=\u00bbon|desktop\u00bb border_color_all_image__hover=\u00bb#F6F1EC\u00bb button_border_color__hover_enabled=\u00bbon|desktop\u00bb button_border_color__hover=\u00bb#f2b437&#8243; button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#F6F1EC\u00bb button_bg_color__hover_enabled=\u00bbon|desktop\u00bb button_bg_color__hover=\u00bb#ffb73a\u00bb button_bg_enable_color__hover=\u00bbon\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/dondivi_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text module_class=\u00bbpa-toggle-text\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p>Ubicada en la Avenida Bush N\u00b0 1873 en Miraflores en La Paz, Bolivia.<\/p>\n<p>La estructura de la Parroquia est\u00e1 conformada por dos c\u00fapulas troncoc\u00f3nicas de generatriz coseno hiperb\u00f3lico enfrentadas. El hecho de tener una geometr\u00eda troncoc\u00f3nica les da a las c\u00e1scaras doble curvatura en cada punto, lo que las hace resistentes al pandeo localizado.<\/p>\n<p>Las c\u00e1scaras fueron construidas utilizando la t\u00e9cnica del fibrocemento que b\u00e1sicamente consiste en construir un encofrado de cemento reforzado sobre el que se vierte el hormig\u00f3n armado. El resultado son c\u00e1scaras nervadas en las que queda el encofrado de hormig\u00f3n visto en su interior. Adicionalmente la cubierta del techo tiene dos peque\u00f1as c\u00e1scaras, tambi\u00e9n troncoc\u00f3nicas, no nervadas. La cubierta cubre una superficie \u00fatil total de 540 metros cuadrados.<\/p>\n<p>La Parroquia Coraz\u00f3n de Mar\u00eda fue galardona con el premio a la mejor construcci\u00f3n monumental el a\u00f1o 1972 por los \u00abAmigos de la Ciudad\u00bb. La concepci\u00f3n arquitect\u00f3nica, el dise\u00f1o estructural y la construcci\u00f3n fueron realizadas \u00edntegramente por el ingeniero boliviano don Mario Galindo Rojas.<\/p>\n<p>Queremos hacer una Menci\u00f3n Honor\u00edfica especial al padre Pedro Ria\u00f1o, quien fue el art\u00edfice para impulsar la construcci\u00f3n consiguiendo los fondos necesarios s\u00f3lo con limosnas y donaciones. La Parroquia es el resultado de la decisi\u00f3n conjunta del padre Ria\u00f1o y del ingeniero Galindo de hacer, en la total adversidad, una obra dedicada a Dios.<\/p>\n<p>Lamentablemente la parroquia est\u00e1 inconclusa pues ten\u00eda que ser pintada de blanco inmaculado tanto por dentro como por fuera, los bancos ten\u00edan un dise\u00f1o especial, la torre ten\u00eda que ser m\u00e1s alta y estaba dise\u00f1ada una escultura de Jesucristo que nunca se pudo esculpir, entre muchos otros detalles faltantes. Todo el trabajo se detuvo cuando el padre Pedro fue trasladado al peque\u00f1o pueblo de Bol\u00edvar por instrucciones de la iglesia. Sin embargo, lo m\u00e1s importante de la Parroquia se pudo construir y, hoy en d\u00eda, es una realidad que perdurar\u00e1 por muchos siglos para la alabanza de Dios.<\/p>\n<p>El padre Pedro fue un gran sacerdote espa\u00f1ol que hizo much\u00edsimo por la salvaci\u00f3n de las almas en Bolivia. Su legado va mucho m\u00e1s all\u00e1 de la construcci\u00f3n de la Parroquia. Otra de sus grandes haza\u00f1as est\u00e1 en el pueblo de Bol\u00edvar que lo transform\u00f3 de ser un peque\u00f1o pueblo pobre a uno grande y pujante. Pese a no haber podido concluir la Parroquia, el padre Pedro fue muy feliz de ir a Bol\u00edvar pues pudo hacer mucha obra en representaci\u00f3n de nuestro se\u00f1or Jesucristo. Con el mayor respeto y cari\u00f1o va nuestro sincero saludo y eterno agradecimiento a tan digno sacerdote all\u00e1 en el cielo donde se encuentra.<\/p>\n<p>Tambi\u00e9n queremos mencionar al maestro Florentino L\u00f3pez quien dirigi\u00f3 a los obreros de la construcci\u00f3n y al picapedrero maestro Pedro Argote qui\u00e9n esculpi\u00f3 todas las piedras del muro inferior en una obra de arte sin precedentes.<\/p>\n<p>Finalmente, no podemos dejar de mencionar al artista y arquitecto boliviano don Ricardo P\u00e9rez Alcal\u00e1 qui\u00e9n ayud\u00f3 en innumerables detalles y pint\u00f3 varios cuadros de la parroquia que guardamos celosamente en Galindo Ingenier\u00eda.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><span>Fecha: 1972 \u2013 La Paz, Bolivia.<\/span><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb17px||21px|||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_divider color=\u00bb#E09900&#8243; divider_weight=\u00bb4px\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT|800|||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb54px\u00bb text_line_height=\u00bb1.2em\u00bb text_orientation=\u00bbcenter\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb\u00bb width_last_edited=\u00bbon|phone\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb54px\u00bb text_font_size_phone=\u00bb34px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p>Torres Gundlach<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][dondivi_gallery gallery_ids=\u00bb405641,405638,405642,293,405639,296,405640,294&#8243; image_count=\u00bb3&#8243; load_more=\u00bbon\u00bb load_more_text=\u00bbCargar M\u00e1s\u00bb show_pagination=\u00bboff\u00bb image_zoom=\u00bbon\u00bb overlay=\u00bbon\u00bb on_click=\u00bblightbox\u00bb lightbox_title=\u00bboff\u00bb lightbox_caption=\u00bboff\u00bb hover_overlay_color=\u00bbrgba(28,55,101,0.71)\u00bb hover_icon=\u00bb&#x4c;||divi||400&#8243; hover_icon_color=\u00bb#f79839&#8243; hover_icon_width=\u00bb35px\u00bb effect_opacity=\u00bbon\u00bb layout_columns_tablet=\u00bb\u00bb layout_columns_phone=\u00bb2&#8243; layout_columns_last_edited=\u00bbon|phone\u00bb layout_gap_tablet=\u00bb20px\u00bb layout_gap_phone=\u00bb10px\u00bb layout_gap_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbGALINDOFONT|600|||||||\u00bb title_text_color=\u00bb#FFCB58&#8243; title_font_size=\u00bb17px\u00bb caption_font=\u00bbGALINDOFONT||||||||\u00bb caption_font_size=\u00bb13px\u00bb caption_line_height=\u00bb1.3em\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#F6F1EC\u00bb button_bg_color=\u00bb#f79839&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#f4c538&#8243; button_border_radius=\u00bb50px\u00bb button_font=\u00bbGALINDOFONT||||||||\u00bb button_use_icon=\u00bboff\u00bb button_alignment=\u00bbcenter\u00bb button_custom_margin=\u00bb||||false|false\u00bb button_custom_padding=\u00bb7px|37px|7px|37px|true|true\u00bb image_icon_custom_margin=\u00bb||0px||false|false\u00bb image_icon_custom_padding=\u00bb||0px||false|false\u00bb filter_custom_padding_tablet=\u00bb||10px||false|false\u00bb filter_custom_padding_phone=\u00bb|5px|10px|5px|false|true\u00bb filter_custom_padding_last_edited=\u00bbon|phone\u00bb max_width=\u00bb709px\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|desktop\u00bb module_alignment=\u00bbcenter\u00bb animation_style=\u00bbfade\u00bb animation_duration=\u00bb500ms\u00bb title_font_size_tablet=\u00bb\u00bb title_font_size_phone=\u00bb18px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb caption_text_align_phone=\u00bbcenter\u00bb caption_text_align_last_edited=\u00bboff|phone\u00bb caption_font_size_tablet=\u00bb15px\u00bb caption_font_size_phone=\u00bb13px\u00bb caption_font_size_last_edited=\u00bbon|phone\u00bb filter_font_size_tablet=\u00bb20px\u00bb filter_font_size_phone=\u00bb17px\u00bb filter_font_size_last_edited=\u00bbon|phone\u00bb border_radii_image=\u00bbon|10px|10px|10px|10px\u00bb border_color_all_image=\u00bbRGBA(255,255,255,0)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb filter_text_color__hover_enabled=\u00bbon|hover\u00bb filter_text_color__hover=\u00bb#764699&#8243; border_color_all_image__hover_enabled=\u00bbon|desktop\u00bb border_color_all_image__hover=\u00bb#F6F1EC\u00bb button_border_color__hover_enabled=\u00bbon|desktop\u00bb button_border_color__hover=\u00bb#f2b437&#8243; button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#F6F1EC\u00bb button_bg_color__hover_enabled=\u00bbon|desktop\u00bb button_bg_color__hover=\u00bb#ffb73a\u00bb button_bg_enable_color__hover=\u00bbon\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/dondivi_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text module_class=\u00bbpa-toggle-text\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>Se trata de un edificio de oficinas constituido por dos torres, ubicado en la esquina de las calles Reyes Ortiz y Federico Zuazo en la ciudad de La Paz &#8211; Bolivia.<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>La \u00abTorre Oeste\u00bb es uno de los edificios m\u00e1s altos de Bolivia ya que cuenta con 104 metros de altura teniendo una capacidad sismorresistente elevada. Cabe se\u00f1alar que a la fecha las torres ya han soportado dos sismos importantes para la ciudad de La Paz, sin presentar <span><a tabindex=\"-1\"><\/a><\/span>ninguna fisura.<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>Una de sus principales caracter\u00edsticas estructurales es que tiene una c\u00e1scara de hormig\u00f3n en la entrada (similar en luz a las c\u00e1scaras de la Iglesia de San Miguel Arc\u00e1ngel, pero mucho m\u00e1s baja en altura, lo que la hace estructuralmente m\u00e1s desafiante). El principio de una c\u00e1scara es que es una estructura curva continua con espesor muy peque\u00f1o, que se soporta por su geometr\u00eda antes que por la resistencia del material con el que est\u00e1 construida.<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>La geometr\u00eda de la c\u00e1scara del edificio est\u00e1 generada con una sucesi\u00f3n de pol\u00edgonos funiculares en catenaria. Por eso es que pudo construirse con tan s\u00f3lo 6 cent\u00edmetros de espesor utilizando hormig\u00f3n de 15 MPa de resistencia caracter\u00edstica.<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>Otra caracter\u00edstica interesante es que la piel de vidrio de la c\u00e1scara es una estructura que se soporta por la resistencia del vidrio empleado como elemento estructural.<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">El proyecto est\u00e1 conformado por dos torres que tienen una superficie total construida de 28,700 metros cuadrados. La \u201cTorre Este\u201d tiene 17 plantas de 550 metros cuadrados, y la \u201cTorre Oeste\u201d tiene 32 plantas de 400 metros cuadrados, el mezanine y los s\u00f3tanos tienen una superficie de 1800 metros cuadrados cada uno.<\/div>\n<div dir=\"auto\">\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Nuestro trabajo consisti\u00f3 en el c\u00e1lculo y dise\u00f1o estructural, as\u00ed como la supervisi\u00f3n de la obra gruesa.<\/div>\n<\/div>\n<p><span><\/span><\/p>\n<p><span><\/span><\/p>\n<ul>\n<li><span>Fecha: 1996 \u2013 La Paz, Bolivia<\/span><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb17px||21px|||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_divider color=\u00bb#E09900&#8243; divider_weight=\u00bb4px\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT|800|||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb54px\u00bb text_line_height=\u00bb1.2em\u00bb text_orientation=\u00bbcenter\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb\u00bb width_last_edited=\u00bbon|phone\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb54px\u00bb text_font_size_phone=\u00bb34px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>Edificio Marbella<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][dondivi_gallery gallery_ids=\u00bb405645,365,405644,405643,366,405646,405647&#8243; image_count=\u00bb3&#8243; load_more=\u00bbon\u00bb load_more_text=\u00bbCargar M\u00e1s\u00bb show_pagination=\u00bboff\u00bb image_zoom=\u00bbon\u00bb overlay=\u00bbon\u00bb on_click=\u00bblightbox\u00bb lightbox_title=\u00bboff\u00bb lightbox_caption=\u00bboff\u00bb hover_overlay_color=\u00bbrgba(28,55,101,0.71)\u00bb hover_icon=\u00bb&#x4c;||divi||400&#8243; hover_icon_color=\u00bb#f79839&#8243; hover_icon_width=\u00bb35px\u00bb effect_opacity=\u00bbon\u00bb layout_gap_tablet=\u00bb20px\u00bb layout_gap_phone=\u00bb10px\u00bb layout_gap_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbGALINDOFONT|600|||||||\u00bb title_text_color=\u00bb#FFCB58&#8243; title_font_size=\u00bb17px\u00bb caption_font=\u00bbGALINDOFONT||||||||\u00bb caption_font_size=\u00bb13px\u00bb caption_line_height=\u00bb1.3em\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#F6F1EC\u00bb button_bg_color=\u00bb#f79839&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#f4c538&#8243; button_border_radius=\u00bb50px\u00bb button_font=\u00bbGALINDOFONT||||||||\u00bb button_use_icon=\u00bboff\u00bb button_alignment=\u00bbcenter\u00bb button_custom_margin=\u00bb||||false|false\u00bb button_custom_padding=\u00bb7px|37px|7px|37px|true|true\u00bb image_icon_custom_margin=\u00bb||0px||false|false\u00bb image_icon_custom_padding=\u00bb||0px||false|false\u00bb filter_custom_padding_tablet=\u00bb||10px||false|false\u00bb filter_custom_padding_phone=\u00bb|5px|10px|5px|false|true\u00bb filter_custom_padding_last_edited=\u00bbon|phone\u00bb max_width=\u00bb709px\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|desktop\u00bb module_alignment=\u00bbcenter\u00bb animation_style=\u00bbfade\u00bb animation_duration=\u00bb500ms\u00bb title_font_size_tablet=\u00bb\u00bb title_font_size_phone=\u00bb18px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb caption_text_align_phone=\u00bbcenter\u00bb caption_text_align_last_edited=\u00bboff|phone\u00bb caption_font_size_tablet=\u00bb15px\u00bb caption_font_size_phone=\u00bb13px\u00bb caption_font_size_last_edited=\u00bbon|phone\u00bb filter_font_size_tablet=\u00bb20px\u00bb filter_font_size_phone=\u00bb17px\u00bb filter_font_size_last_edited=\u00bbon|phone\u00bb border_radii_image=\u00bbon|10px|10px|10px|10px\u00bb border_color_all_image=\u00bbRGBA(255,255,255,0)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb filter_text_color__hover_enabled=\u00bbon|hover\u00bb filter_text_color__hover=\u00bb#764699&#8243; border_color_all_image__hover_enabled=\u00bbon|desktop\u00bb border_color_all_image__hover=\u00bb#F6F1EC\u00bb button_border_color__hover_enabled=\u00bbon|desktop\u00bb button_border_color__hover=\u00bb#f2b437&#8243; button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#F6F1EC\u00bb button_bg_color__hover_enabled=\u00bbon|desktop\u00bb button_bg_color__hover=\u00bb#ffb73a\u00bb button_bg_enable_color__hover=\u00bbon\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/dondivi_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text module_class=\u00bbpa-toggle-text\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>Se trata de un edificio destinado a tres usos, los primeros pisos se utilizan para una galer\u00eda comercial y una plaza de comidas. Una segunda parte destinada a un hotel. Y finalmente los \u00faltimos pisos destinados a departamentos privados. El edificio consta de 11 plantas y una superficie total construida de 7,100 [m2].<\/span><\/p>\n<p><span><\/span><\/p>\n<ul>\n<li><span>Fecha: 2015 \u2013 La Paz, Bolivia<\/span><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb17px||21px|||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_divider color=\u00bb#E09900&#8243; divider_weight=\u00bb4px\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT|800|||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb54px\u00bb text_line_height=\u00bb1.2em\u00bb text_orientation=\u00bbcenter\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb\u00bb width_last_edited=\u00bbon|phone\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb54px\u00bb text_font_size_phone=\u00bb34px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>Torre El Shaddai<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][dondivi_gallery gallery_ids=\u00bb405648,405649,405650,405651,694,373,375&#8243; image_count=\u00bb3&#8243; load_more=\u00bbon\u00bb load_more_text=\u00bbCargar M\u00e1s\u00bb show_pagination=\u00bboff\u00bb image_zoom=\u00bbon\u00bb overlay=\u00bbon\u00bb on_click=\u00bblightbox\u00bb lightbox_title=\u00bboff\u00bb lightbox_caption=\u00bboff\u00bb hover_overlay_color=\u00bbrgba(28,55,101,0.71)\u00bb hover_icon=\u00bb&#x4c;||divi||400&#8243; hover_icon_color=\u00bb#f79839&#8243; hover_icon_width=\u00bb35px\u00bb effect_opacity=\u00bbon\u00bb layout_columns_tablet=\u00bb\u00bb layout_columns_phone=\u00bb2&#8243; layout_columns_last_edited=\u00bbon|phone\u00bb layout_gap_tablet=\u00bb20px\u00bb layout_gap_phone=\u00bb10px\u00bb layout_gap_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbGALINDOFONT|600|||||||\u00bb title_text_color=\u00bb#FFCB58&#8243; title_font_size=\u00bb17px\u00bb caption_font=\u00bbGALINDOFONT||||||||\u00bb caption_font_size=\u00bb13px\u00bb caption_line_height=\u00bb1.3em\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#F6F1EC\u00bb button_bg_color=\u00bb#f79839&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#f4c538&#8243; button_border_radius=\u00bb50px\u00bb button_font=\u00bbGALINDOFONT||||||||\u00bb button_use_icon=\u00bboff\u00bb button_alignment=\u00bbcenter\u00bb button_custom_margin=\u00bb||||false|false\u00bb button_custom_padding=\u00bb7px|37px|7px|37px|true|true\u00bb image_icon_custom_margin=\u00bb||0px||false|false\u00bb image_icon_custom_padding=\u00bb||0px||false|false\u00bb filter_custom_padding_tablet=\u00bb||10px||false|false\u00bb filter_custom_padding_phone=\u00bb|5px|10px|5px|false|true\u00bb filter_custom_padding_last_edited=\u00bbon|phone\u00bb max_width=\u00bb709px\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|desktop\u00bb module_alignment=\u00bbcenter\u00bb animation_style=\u00bbfade\u00bb animation_duration=\u00bb500ms\u00bb title_font_size_tablet=\u00bb\u00bb title_font_size_phone=\u00bb18px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb caption_text_align_phone=\u00bbcenter\u00bb caption_text_align_last_edited=\u00bboff|phone\u00bb caption_font_size_tablet=\u00bb15px\u00bb caption_font_size_phone=\u00bb13px\u00bb caption_font_size_last_edited=\u00bbon|phone\u00bb filter_font_size_tablet=\u00bb20px\u00bb filter_font_size_phone=\u00bb17px\u00bb filter_font_size_last_edited=\u00bbon|phone\u00bb border_radii_image=\u00bbon|10px|10px|10px|10px\u00bb border_color_all_image=\u00bbRGBA(255,255,255,0)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb filter_text_color__hover_enabled=\u00bbon|hover\u00bb filter_text_color__hover=\u00bb#764699&#8243; border_color_all_image__hover_enabled=\u00bbon|desktop\u00bb border_color_all_image__hover=\u00bb#F6F1EC\u00bb button_border_color__hover_enabled=\u00bbon|desktop\u00bb button_border_color__hover=\u00bb#f2b437&#8243; button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#F6F1EC\u00bb button_bg_color__hover_enabled=\u00bbon|desktop\u00bb button_bg_color__hover=\u00bb#ffb73a\u00bb button_bg_enable_color__hover=\u00bbon\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/dondivi_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text module_class=\u00bbpa-toggle-text\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>Se trata de un edificio que est\u00e1 al borde de un barranco de 30 metros de desnivel, ubicado en la Avenida Saavedra, zona Miraflores de La Paz &#8211; Bolivia.<\/p>\n<p>Tiene una arquitectura desafiante ya que cuenta con un voladizo de 4 pisos de altura y hasta 6 metros de luz.<\/p>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>Lo <span><a tabindex=\"-1\"><\/a><\/span>notable de este proyecto es que la geometr\u00eda no es lo que se recomienda para ser sismorresistente, por lo que, internamente se tuvieron que disponer mecanismos especiales para resistir el esfuerzo torsor que producen los sismos. De esta forma, se ha conseguido un edificio, que con estas exigencias estructurales, es capaz de soportar sismos mayores a los especificados en las normas.<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>La parte posterior del edificio tiene una vista panor\u00e1mica donde se pueden ver los Puentes Trillizos, la Av. Arce, la Av. del Poeta y gran parte de nuestra hermosa ciudad.<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">El edificio cuenta con 2 s\u00f3tanos y 8 pisos, dando un total de 10 niveles.<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Nuestro trabajo consisti\u00f3 en el dise\u00f1o y c\u00e1lculo estructural, y la supervisi\u00f3n parcial de la obra, que estuvo a cargo de nuestro PhD. MSc. Ing. Mario Galindo Queralt.<\/div>\n<\/div>\n<p><span><\/span><\/p>\n<p><span><\/span><\/p>\n<ul>\n<li><span>Fecha: 2013 \u2013 La Paz, Bolivia<\/span><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; module_id=\u00bbmetalica\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttp:\/\/galindoingenieria.com\/wp-content\/uploads\/2023\/04\/3-1.jpg\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAVENIR REAL|800|||||||\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb54px\u00bb text_orientation=\u00bbcenter\u00bb text_font_last_edited=\u00bboff|desktop\u00bb text_font_size_tablet=\u00bb\u00bb text_font_size_phone=\u00bb29px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p>Estructuras Met\u00e1licas<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT|800|||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb54px\u00bb text_line_height=\u00bb1.2em\u00bb text_orientation=\u00bbcenter\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb\u00bb width_last_edited=\u00bbon|phone\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb54px\u00bb text_font_size_phone=\u00bb34px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>Soboce &#8211; Almac\u00e9n de Materias Primas<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][dondivi_gallery gallery_ids=\u00bb405653,405654,405652,405655,382,211,405656,405657,405658,405659&#8243; image_count=\u00bb3&#8243; load_more=\u00bbon\u00bb load_more_text=\u00bbCargar M\u00e1s\u00bb show_pagination=\u00bboff\u00bb image_zoom=\u00bbon\u00bb overlay=\u00bbon\u00bb on_click=\u00bblightbox\u00bb lightbox_title=\u00bboff\u00bb lightbox_caption=\u00bboff\u00bb hover_overlay_color=\u00bbrgba(28,55,101,0.71)\u00bb hover_icon=\u00bb&#x4c;||divi||400&#8243; hover_icon_color=\u00bb#f79839&#8243; hover_icon_width=\u00bb35px\u00bb effect_opacity=\u00bbon\u00bb layout_columns_tablet=\u00bb\u00bb layout_columns_phone=\u00bb2&#8243; layout_columns_last_edited=\u00bbon|phone\u00bb layout_gap_tablet=\u00bb20px\u00bb layout_gap_phone=\u00bb10px\u00bb layout_gap_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbGALINDOFONT|600|||||||\u00bb title_text_color=\u00bb#FFCB58&#8243; title_font_size=\u00bb17px\u00bb caption_font=\u00bbGALINDOFONT||||||||\u00bb caption_font_size=\u00bb13px\u00bb caption_line_height=\u00bb1.3em\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#F6F1EC\u00bb button_bg_color=\u00bb#f79839&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#f4c538&#8243; button_border_radius=\u00bb50px\u00bb button_font=\u00bbGALINDOFONT||||||||\u00bb button_use_icon=\u00bboff\u00bb button_alignment=\u00bbcenter\u00bb button_custom_margin=\u00bb||||false|false\u00bb button_custom_padding=\u00bb7px|37px|7px|37px|true|true\u00bb image_icon_custom_margin=\u00bb||0px||false|false\u00bb image_icon_custom_padding=\u00bb||0px||false|false\u00bb filter_custom_padding_tablet=\u00bb||10px||false|false\u00bb filter_custom_padding_phone=\u00bb|5px|10px|5px|false|true\u00bb filter_custom_padding_last_edited=\u00bbon|phone\u00bb max_width=\u00bb709px\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|desktop\u00bb module_alignment=\u00bbcenter\u00bb animation_style=\u00bbfade\u00bb animation_duration=\u00bb500ms\u00bb title_font_size_tablet=\u00bb\u00bb title_font_size_phone=\u00bb18px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb caption_text_align_phone=\u00bbcenter\u00bb caption_text_align_last_edited=\u00bboff|phone\u00bb caption_font_size_tablet=\u00bb15px\u00bb caption_font_size_phone=\u00bb13px\u00bb caption_font_size_last_edited=\u00bbon|phone\u00bb filter_font_size_tablet=\u00bb20px\u00bb filter_font_size_phone=\u00bb17px\u00bb filter_font_size_last_edited=\u00bbon|phone\u00bb border_radii_image=\u00bbon|10px|10px|10px|10px\u00bb border_color_all_image=\u00bbRGBA(255,255,255,0)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb filter_text_color__hover_enabled=\u00bbon|hover\u00bb filter_text_color__hover=\u00bb#764699&#8243; border_color_all_image__hover_enabled=\u00bbon|desktop\u00bb border_color_all_image__hover=\u00bb#F6F1EC\u00bb button_border_color__hover_enabled=\u00bbon|desktop\u00bb button_border_color__hover=\u00bb#f2b437&#8243; button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#F6F1EC\u00bb button_bg_color__hover_enabled=\u00bbon|desktop\u00bb button_bg_color__hover=\u00bb#ffb73a\u00bb button_bg_enable_color__hover=\u00bbon\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/dondivi_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text module_class=\u00bbpa-toggle-text\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><span>Participamos en la ampliaci\u00f3n de la planta de producci\u00f3n de cemento Viacha, un proyecto m\u00faltiple de gran escala. Nuestro equipo fue responsable del dise\u00f1o de diversas \u00e1reas, incluyendo una cubierta met\u00e1lica para el almac\u00e9n de materias primas, sistemas de fajas de transporte, apilador, reclamador y muros de contenci\u00f3n<\/span>.<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">La joya de esta ampliaci\u00f3n es, sin duda, la cubierta <span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><a class=\"html-a xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\" tabindex=\"-1\"><\/a><\/span>met\u00e1lica, una estructura destacable por su ingenier\u00eda y dimensiones. Construida con 15 p\u00f3rticos met\u00e1licos triarticulados, esta cubierta presenta una directriz de coseno hiperb\u00f3lico, con una luz de 58 metros, una longitud de 156 metros y una altura de 30 metros, abarcando una superficie de aproximadamente 9,000 m\u00b2. \u00a1Es tan grande que podr\u00eda albergar una cancha de f\u00fatbol sin problemas!<\/div>\n<div dir=\"auto\">\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">La estructura completa pesa 450 toneladas.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Estamos orgullosos de haber contribuido a este proyecto y de continuar siendo vanguardia en la ingenier\u00eda boliviana.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<ul>\n<li><span>Fecha: 2016 &#8211; La Paz, Bolivia<\/span><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb17px||21px|||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_divider color=\u00bb#E09900&#8243; divider_weight=\u00bb4px\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT|800|||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb54px\u00bb text_line_height=\u00bb1.2em\u00bb text_orientation=\u00bbcenter\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb\u00bb width_last_edited=\u00bbon|phone\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb54px\u00bb text_font_size_phone=\u00bb34px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>Torre Unitel<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][dondivi_gallery gallery_ids=\u00bb386,387,405664,405661,405662,405663&#8243; image_count=\u00bb3&#8243; load_more=\u00bbon\u00bb load_more_text=\u00bbCargar M\u00e1s\u00bb show_pagination=\u00bboff\u00bb image_zoom=\u00bbon\u00bb overlay=\u00bbon\u00bb on_click=\u00bblightbox\u00bb lightbox_title=\u00bboff\u00bb lightbox_caption=\u00bboff\u00bb hover_overlay_color=\u00bbrgba(28,55,101,0.71)\u00bb hover_icon=\u00bb&#x4c;||divi||400&#8243; hover_icon_color=\u00bb#f79839&#8243; hover_icon_width=\u00bb35px\u00bb effect_opacity=\u00bbon\u00bb layout_columns_tablet=\u00bb\u00bb layout_columns_phone=\u00bb2&#8243; layout_columns_last_edited=\u00bbon|phone\u00bb layout_gap_tablet=\u00bb20px\u00bb layout_gap_phone=\u00bb10px\u00bb layout_gap_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbGALINDOFONT|600|||||||\u00bb title_text_color=\u00bb#FFCB58&#8243; title_font_size=\u00bb17px\u00bb caption_font=\u00bbGALINDOFONT||||||||\u00bb caption_font_size=\u00bb13px\u00bb caption_line_height=\u00bb1.3em\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#F6F1EC\u00bb button_bg_color=\u00bb#f79839&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#f4c538&#8243; button_border_radius=\u00bb50px\u00bb button_font=\u00bbGALINDOFONT||||||||\u00bb button_use_icon=\u00bboff\u00bb button_alignment=\u00bbcenter\u00bb button_custom_margin=\u00bb||||false|false\u00bb button_custom_padding=\u00bb7px|37px|7px|37px|true|true\u00bb image_icon_custom_margin=\u00bb||0px||false|false\u00bb image_icon_custom_padding=\u00bb||0px||false|false\u00bb filter_custom_padding_tablet=\u00bb||10px||false|false\u00bb filter_custom_padding_phone=\u00bb|5px|10px|5px|false|true\u00bb filter_custom_padding_last_edited=\u00bbon|phone\u00bb max_width=\u00bb709px\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|desktop\u00bb module_alignment=\u00bbcenter\u00bb animation_style=\u00bbfade\u00bb animation_duration=\u00bb500ms\u00bb title_font_size_tablet=\u00bb\u00bb title_font_size_phone=\u00bb18px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb caption_text_align_phone=\u00bbcenter\u00bb caption_text_align_last_edited=\u00bboff|phone\u00bb caption_font_size_tablet=\u00bb15px\u00bb caption_font_size_phone=\u00bb13px\u00bb caption_font_size_last_edited=\u00bbon|phone\u00bb filter_font_size_tablet=\u00bb20px\u00bb filter_font_size_phone=\u00bb17px\u00bb filter_font_size_last_edited=\u00bbon|phone\u00bb border_radii_image=\u00bbon|10px|10px|10px|10px\u00bb border_color_all_image=\u00bbRGBA(255,255,255,0)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb filter_text_color__hover_enabled=\u00bbon|hover\u00bb filter_text_color__hover=\u00bb#764699&#8243; border_color_all_image__hover_enabled=\u00bbon|desktop\u00bb border_color_all_image__hover=\u00bb#F6F1EC\u00bb button_border_color__hover_enabled=\u00bbon|desktop\u00bb button_border_color__hover=\u00bb#f2b437&#8243; button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#F6F1EC\u00bb button_bg_color__hover_enabled=\u00bbon|desktop\u00bb button_bg_color__hover=\u00bb#ffb73a\u00bb button_bg_enable_color__hover=\u00bbon\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/dondivi_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text module_class=\u00bbpa-toggle-text\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>Se trata de una torre atirantada destinada a soportar las antenas de trasmisi\u00f3n del canal de televisi\u00f3n Unitel. La torre est\u00e1 constituida por un tubo de acero de 120 metros de altura y 30 cent\u00edmetros de di\u00e1metro, sostenida por cables de acero que tienen una marcada curvatura en <span><a tabindex=\"-1\"><\/a><\/span>su catenaria.<\/p>\n<p>Hemos elegido publicar este proyecto, no porque se trate de una estructura grande, sino porque su dise\u00f1o, an\u00e1lisis y construcci\u00f3n han presentado desaf\u00edos estructurales importantes.<\/p>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>El problema estructural es que un cable fuertemente curvo presenta un comportamiento altamente no lineal, ya que cuando en \u00e9l act\u00faan fuerzas de viento, el cable cambia su forma y, por tanto, tiene un funcionamiento estructural diferente al que ten\u00eda con la geometr\u00eda inicial.<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>Este comportamiento geom\u00e9trico no lineal implica que las ecuaciones de gobierno de la estructura cambian en el tiempo, por lo que deben resolverse mediante m\u00e9todos num\u00e9ricos iterativos avanzados.<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>Como referencia podemos indicar que, a la m\u00e1xima velocidad de viento considerada, la marcada flecha de la catenaria de los cables se invierte por completo, presentando su curvatura hacia arriba; pero notablemente durante todo este proceso la torre casi no se mueve.<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Nuestro trabajo consisti\u00f3 en el dise\u00f1o, el an\u00e1lisis y la construcci\u00f3n de la torre.<\/div>\n<\/div>\n<p><span>\u00a0<\/span><\/p>\n<ul>\n<li><span>Fecha: 1992 \u2013 Santa Cruz, Bolivia<\/span><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb17px||21px|||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_divider color=\u00bb#E09900&#8243; divider_weight=\u00bb4px\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT|800|||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb54px\u00bb text_line_height=\u00bb1.2em\u00bb text_orientation=\u00bbcenter\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb\u00bb width_last_edited=\u00bbon|phone\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb54px\u00bb text_font_size_phone=\u00bb34px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>Estructura de Metal Pollos Copacaba<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][dondivi_gallery gallery_ids=\u00bb391,389&#8243; image_count=\u00bb3&#8243; load_more=\u00bbon\u00bb load_more_text=\u00bbCargar M\u00e1s\u00bb show_pagination=\u00bboff\u00bb image_zoom=\u00bbon\u00bb overlay=\u00bbon\u00bb on_click=\u00bblightbox\u00bb lightbox_title=\u00bboff\u00bb lightbox_caption=\u00bboff\u00bb hover_overlay_color=\u00bbrgba(28,55,101,0.71)\u00bb hover_icon=\u00bb&#x4c;||divi||400&#8243; hover_icon_color=\u00bb#f79839&#8243; hover_icon_width=\u00bb35px\u00bb effect_opacity=\u00bbon\u00bb layout_gap_tablet=\u00bb20px\u00bb layout_gap_phone=\u00bb10px\u00bb layout_gap_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbGALINDOFONT|600|||||||\u00bb title_text_color=\u00bb#FFCB58&#8243; title_font_size=\u00bb17px\u00bb caption_font=\u00bbGALINDOFONT||||||||\u00bb caption_font_size=\u00bb13px\u00bb caption_line_height=\u00bb1.3em\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#F6F1EC\u00bb button_bg_color=\u00bb#f79839&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#f4c538&#8243; button_border_radius=\u00bb50px\u00bb button_font=\u00bbGALINDOFONT||||||||\u00bb button_use_icon=\u00bboff\u00bb button_alignment=\u00bbcenter\u00bb button_custom_margin=\u00bb||||false|false\u00bb button_custom_padding=\u00bb7px|37px|7px|37px|true|true\u00bb image_icon_custom_margin=\u00bb||0px||false|false\u00bb image_icon_custom_padding=\u00bb||0px||false|false\u00bb filter_custom_padding_tablet=\u00bb||10px||false|false\u00bb filter_custom_padding_phone=\u00bb|5px|10px|5px|false|true\u00bb filter_custom_padding_last_edited=\u00bbon|phone\u00bb max_width=\u00bb709px\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|desktop\u00bb module_alignment=\u00bbcenter\u00bb animation_style=\u00bbfade\u00bb animation_duration=\u00bb500ms\u00bb title_font_size_tablet=\u00bb\u00bb title_font_size_phone=\u00bb18px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb caption_text_align_phone=\u00bbcenter\u00bb caption_text_align_last_edited=\u00bboff|phone\u00bb caption_font_size_tablet=\u00bb15px\u00bb caption_font_size_phone=\u00bb13px\u00bb caption_font_size_last_edited=\u00bbon|phone\u00bb filter_font_size_tablet=\u00bb20px\u00bb filter_font_size_phone=\u00bb17px\u00bb filter_font_size_last_edited=\u00bbon|phone\u00bb border_radii_image=\u00bbon|10px|10px|10px|10px\u00bb border_color_all_image=\u00bbRGBA(255,255,255,0)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb filter_text_color__hover_enabled=\u00bbon|hover\u00bb filter_text_color__hover=\u00bb#764699&#8243; border_color_all_image__hover_enabled=\u00bbon|desktop\u00bb border_color_all_image__hover=\u00bb#F6F1EC\u00bb button_border_color__hover_enabled=\u00bbon|desktop\u00bb button_border_color__hover=\u00bb#f2b437&#8243; button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#F6F1EC\u00bb button_bg_color__hover_enabled=\u00bbon|desktop\u00bb button_bg_color__hover=\u00bb#ffb73a\u00bb button_bg_enable_color__hover=\u00bbon\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/dondivi_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text module_class=\u00bbpa-toggle-text\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>Es una estructura met\u00e1lica destinada a cubrir el comedor de pollos Copacabana con una superficie de 180 [m2]. Lo interesante de esta estructura es que el techo solo se apoya en 3 de sus 4 esquinas, dejando por tanto una de sus esquinas en voladizo.<\/span><\/p>\n<p><span><\/span><\/p>\n<ul>\n<li><span>Fecha: 1999 \u2013 La Paz, Bolivia<\/span><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb17px||21px|||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_divider color=\u00bb#E09900&#8243; divider_weight=\u00bb4px\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT|800|||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb54px\u00bb text_line_height=\u00bb1.2em\u00bb text_orientation=\u00bbcenter\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb\u00bb width_last_edited=\u00bbon|phone\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb54px\u00bb text_font_size_phone=\u00bb34px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>SOBOCE Warnes<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][dondivi_gallery gallery_ids=\u00bb395,396&#8243; image_count=\u00bb3&#8243; load_more=\u00bbon\u00bb load_more_text=\u00bbCargar M\u00e1s\u00bb show_pagination=\u00bboff\u00bb image_zoom=\u00bbon\u00bb overlay=\u00bbon\u00bb on_click=\u00bblightbox\u00bb lightbox_title=\u00bboff\u00bb lightbox_caption=\u00bboff\u00bb hover_overlay_color=\u00bbrgba(28,55,101,0.71)\u00bb hover_icon=\u00bb&#x4c;||divi||400&#8243; hover_icon_color=\u00bb#f79839&#8243; hover_icon_width=\u00bb35px\u00bb effect_opacity=\u00bbon\u00bb layout_gap_tablet=\u00bb20px\u00bb layout_gap_phone=\u00bb10px\u00bb layout_gap_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbGALINDOFONT|600|||||||\u00bb title_text_color=\u00bb#FFCB58&#8243; title_font_size=\u00bb17px\u00bb caption_font=\u00bbGALINDOFONT||||||||\u00bb caption_font_size=\u00bb13px\u00bb caption_line_height=\u00bb1.3em\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#F6F1EC\u00bb button_bg_color=\u00bb#f79839&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#f4c538&#8243; button_border_radius=\u00bb50px\u00bb button_font=\u00bbGALINDOFONT||||||||\u00bb button_use_icon=\u00bboff\u00bb button_alignment=\u00bbcenter\u00bb button_custom_margin=\u00bb||||false|false\u00bb button_custom_padding=\u00bb7px|37px|7px|37px|true|true\u00bb image_icon_custom_margin=\u00bb||0px||false|false\u00bb image_icon_custom_padding=\u00bb||0px||false|false\u00bb filter_custom_padding_tablet=\u00bb||10px||false|false\u00bb filter_custom_padding_phone=\u00bb|5px|10px|5px|false|true\u00bb filter_custom_padding_last_edited=\u00bbon|phone\u00bb max_width=\u00bb709px\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|desktop\u00bb module_alignment=\u00bbcenter\u00bb animation_style=\u00bbfade\u00bb animation_duration=\u00bb500ms\u00bb title_font_size_tablet=\u00bb\u00bb title_font_size_phone=\u00bb18px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb caption_text_align_phone=\u00bbcenter\u00bb caption_text_align_last_edited=\u00bboff|phone\u00bb caption_font_size_tablet=\u00bb15px\u00bb caption_font_size_phone=\u00bb13px\u00bb caption_font_size_last_edited=\u00bbon|phone\u00bb filter_font_size_tablet=\u00bb20px\u00bb filter_font_size_phone=\u00bb17px\u00bb filter_font_size_last_edited=\u00bbon|phone\u00bb border_radii_image=\u00bbon|10px|10px|10px|10px\u00bb border_color_all_image=\u00bbRGBA(255,255,255,0)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb filter_text_color__hover_enabled=\u00bbon|hover\u00bb filter_text_color__hover=\u00bb#764699&#8243; border_color_all_image__hover_enabled=\u00bbon|desktop\u00bb border_color_all_image__hover=\u00bb#F6F1EC\u00bb button_border_color__hover_enabled=\u00bbon|desktop\u00bb button_border_color__hover=\u00bb#f2b437&#8243; button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#F6F1EC\u00bb button_bg_color__hover_enabled=\u00bbon|desktop\u00bb button_bg_color__hover=\u00bb#ffb73a\u00bb button_bg_enable_color__hover=\u00bbon\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/dondivi_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text module_class=\u00bbpa-toggle-text\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>El proyecto contempla un techo met\u00e1lico para almacenar el cemento conformado por 8 p\u00f3rticos met\u00e1licos de dos luces de 23 metros y 7 metros de altura, cubriendo una superficie de 2,400 [m2].<\/span><\/p>\n<p><span><\/span><\/p>\n<ul>\n<li><span>Fecha: 2019 \u2013 Santa Cruz, Bolivia<\/span><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb17px||21px|||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_divider color=\u00bb#E09900&#8243; divider_weight=\u00bb4px\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT|800|||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb54px\u00bb text_line_height=\u00bb1.2em\u00bb text_orientation=\u00bbcenter\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb\u00bb width_last_edited=\u00bbon|phone\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb54px\u00bb text_font_size_phone=\u00bb34px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>Techo <\/span><span>\u201cRotativa <\/span><span>La Raz\u00f3n\u201d<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][dondivi_gallery gallery_ids=\u00bb399,398&#8243; image_count=\u00bb3&#8243; load_more=\u00bbon\u00bb load_more_text=\u00bbCargar M\u00e1s\u00bb show_pagination=\u00bboff\u00bb image_zoom=\u00bbon\u00bb overlay=\u00bbon\u00bb on_click=\u00bblightbox\u00bb lightbox_title=\u00bboff\u00bb lightbox_caption=\u00bboff\u00bb hover_overlay_color=\u00bbrgba(28,55,101,0.71)\u00bb hover_icon=\u00bb&#x4c;||divi||400&#8243; hover_icon_color=\u00bb#f79839&#8243; hover_icon_width=\u00bb35px\u00bb effect_opacity=\u00bbon\u00bb layout_gap_tablet=\u00bb20px\u00bb layout_gap_phone=\u00bb10px\u00bb layout_gap_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbGALINDOFONT|600|||||||\u00bb title_text_color=\u00bb#FFCB58&#8243; title_font_size=\u00bb17px\u00bb caption_font=\u00bbGALINDOFONT||||||||\u00bb caption_font_size=\u00bb13px\u00bb caption_line_height=\u00bb1.3em\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#F6F1EC\u00bb button_bg_color=\u00bb#f79839&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#f4c538&#8243; button_border_radius=\u00bb50px\u00bb button_font=\u00bbGALINDOFONT||||||||\u00bb button_use_icon=\u00bboff\u00bb button_alignment=\u00bbcenter\u00bb button_custom_margin=\u00bb||||false|false\u00bb button_custom_padding=\u00bb7px|37px|7px|37px|true|true\u00bb image_icon_custom_margin=\u00bb||0px||false|false\u00bb image_icon_custom_padding=\u00bb||0px||false|false\u00bb filter_custom_padding_tablet=\u00bb||10px||false|false\u00bb filter_custom_padding_phone=\u00bb|5px|10px|5px|false|true\u00bb filter_custom_padding_last_edited=\u00bbon|phone\u00bb max_width=\u00bb709px\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|desktop\u00bb module_alignment=\u00bbcenter\u00bb animation_style=\u00bbfade\u00bb animation_duration=\u00bb500ms\u00bb title_font_size_tablet=\u00bb\u00bb title_font_size_phone=\u00bb18px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb caption_text_align_phone=\u00bbcenter\u00bb caption_text_align_last_edited=\u00bboff|phone\u00bb caption_font_size_tablet=\u00bb15px\u00bb caption_font_size_phone=\u00bb13px\u00bb caption_font_size_last_edited=\u00bbon|phone\u00bb filter_font_size_tablet=\u00bb20px\u00bb filter_font_size_phone=\u00bb17px\u00bb filter_font_size_last_edited=\u00bbon|phone\u00bb border_radii_image=\u00bbon|10px|10px|10px|10px\u00bb border_color_all_image=\u00bbRGBA(255,255,255,0)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb filter_text_color__hover_enabled=\u00bbon|hover\u00bb filter_text_color__hover=\u00bb#764699&#8243; border_color_all_image__hover_enabled=\u00bbon|desktop\u00bb border_color_all_image__hover=\u00bb#F6F1EC\u00bb button_border_color__hover_enabled=\u00bbon|desktop\u00bb button_border_color__hover=\u00bb#f2b437&#8243; button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#F6F1EC\u00bb button_bg_color__hover_enabled=\u00bbon|desktop\u00bb button_bg_color__hover=\u00bb#ffb73a\u00bb button_bg_enable_color__hover=\u00bbon\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/dondivi_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text module_class=\u00bbpa-toggle-text\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>Se trata de un techo met\u00e1lico conformado por arcos en directriz de catenaria para cubrir una luz de 30 metros y altura m\u00e1xima de 15 metros sin apoyos intermedios que ha perdido la instalaci\u00f3n de una rotativa de 12 metros de altura. El edificio cubre un \u00e1rea de 2000 [m2].<\/span><\/p>\n<ul>\n<li><span>Fecha: 2000 \u2013 La Paz, Bolivia<\/span><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; module_id=\u00bbreparacion\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttp:\/\/galindoingenieria.com\/wp-content\/uploads\/2023\/04\/4fix.jpg\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAVENIR REAL|800|||||||\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb54px\u00bb text_orientation=\u00bbcenter\u00bb text_font_last_edited=\u00bboff|desktop\u00bb text_font_size_tablet=\u00bb\u00bb text_font_size_phone=\u00bb29px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>Reparaci\u00f3n de estructuras y patolog\u00eda<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT|800|||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb54px\u00bb text_line_height=\u00bb1.2em\u00bb text_orientation=\u00bbcenter\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb\u00bb width_last_edited=\u00bbon|phone\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb54px\u00bb text_font_size_phone=\u00bb34px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p>Reparaci\u00f3n Edificio El Alc\u00e1zar<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][dondivi_gallery gallery_ids=\u00bb424,425&#8243; image_count=\u00bb3&#8243; load_more=\u00bbon\u00bb load_more_text=\u00bbCargar M\u00e1s\u00bb show_pagination=\u00bboff\u00bb image_zoom=\u00bbon\u00bb overlay=\u00bbon\u00bb on_click=\u00bblightbox\u00bb lightbox_title=\u00bboff\u00bb lightbox_caption=\u00bboff\u00bb hover_overlay_color=\u00bbrgba(28,55,101,0.71)\u00bb hover_icon=\u00bb&#x4c;||divi||400&#8243; hover_icon_color=\u00bb#f79839&#8243; hover_icon_width=\u00bb35px\u00bb effect_opacity=\u00bbon\u00bb layout_gap_tablet=\u00bb20px\u00bb layout_gap_phone=\u00bb10px\u00bb layout_gap_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbGALINDOFONT|600|||||||\u00bb title_text_color=\u00bb#FFCB58&#8243; title_font_size=\u00bb17px\u00bb caption_font=\u00bbGALINDOFONT||||||||\u00bb caption_font_size=\u00bb13px\u00bb caption_line_height=\u00bb1.3em\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#F6F1EC\u00bb button_bg_color=\u00bb#f79839&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#f4c538&#8243; button_border_radius=\u00bb50px\u00bb button_font=\u00bbGALINDOFONT||||||||\u00bb button_use_icon=\u00bboff\u00bb button_alignment=\u00bbcenter\u00bb button_custom_margin=\u00bb||||false|false\u00bb button_custom_padding=\u00bb7px|37px|7px|37px|true|true\u00bb image_icon_custom_margin=\u00bb||0px||false|false\u00bb image_icon_custom_padding=\u00bb||0px||false|false\u00bb filter_custom_padding_tablet=\u00bb||10px||false|false\u00bb filter_custom_padding_phone=\u00bb|5px|10px|5px|false|true\u00bb filter_custom_padding_last_edited=\u00bbon|phone\u00bb max_width=\u00bb709px\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|desktop\u00bb module_alignment=\u00bbcenter\u00bb animation_style=\u00bbfade\u00bb animation_duration=\u00bb500ms\u00bb title_font_size_tablet=\u00bb\u00bb title_font_size_phone=\u00bb18px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb caption_text_align_phone=\u00bbcenter\u00bb caption_text_align_last_edited=\u00bboff|phone\u00bb caption_font_size_tablet=\u00bb15px\u00bb caption_font_size_phone=\u00bb13px\u00bb caption_font_size_last_edited=\u00bbon|phone\u00bb filter_font_size_tablet=\u00bb20px\u00bb filter_font_size_phone=\u00bb17px\u00bb filter_font_size_last_edited=\u00bbon|phone\u00bb border_radii_image=\u00bbon|10px|10px|10px|10px\u00bb border_color_all_image=\u00bbRGBA(255,255,255,0)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb filter_text_color__hover_enabled=\u00bbon|hover\u00bb filter_text_color__hover=\u00bb#764699&#8243; border_color_all_image__hover_enabled=\u00bbon|desktop\u00bb border_color_all_image__hover=\u00bb#F6F1EC\u00bb button_border_color__hover_enabled=\u00bbon|desktop\u00bb button_border_color__hover=\u00bb#f2b437&#8243; button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#F6F1EC\u00bb button_bg_color__hover_enabled=\u00bbon|desktop\u00bb button_bg_color__hover=\u00bb#ffb73a\u00bb button_bg_enable_color__hover=\u00bbon\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/dondivi_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text module_class=\u00bbpa-toggle-text\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<div dir=\"auto\">El edifico El Alc\u00e1zar conformado por dos torres de 18 pisos y 84 departamentos, a finales del 2012 se present\u00f3 el estallido de un pilar. Esto puso en peligro de colapso al edificio por lo que se tuvieron que evacuar alrededor de 800 personas por un a\u00f1o, tiempo en el que realizamos la patolog\u00eda de la estructura y se repararon 25 pilares en 4 plantas de s\u00f3tanos.<\/div>\n<div dir=\"auto\">\n<p>&nbsp;<\/p>\n<\/div>\n<div dir=\"auto\">Patolog\u00eda, supervisi\u00f3n y c\u00e1lculo de la reparaci\u00f3n del edificio realizado por el Phd. <span><a tabindex=\"-1\"><\/a><\/span>MsC. Ing. Mario Galindo Queralt.<\/div>\n<p><span><\/span><\/p>\n<p><span><\/span><\/p>\n<ul>\n<li><span>Fecha: 2013 \u2013 La Paz, Bolivia<\/span><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb17px||21px|||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_divider color=\u00bb#E09900&#8243; divider_weight=\u00bb4px\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT|800|||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb54px\u00bb text_line_height=\u00bb1.2em\u00bb text_orientation=\u00bbcenter\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb\u00bb width_last_edited=\u00bbon|phone\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb54px\u00bb text_font_size_phone=\u00bb34px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p>Torres del Poeta<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][dondivi_gallery gallery_ids=\u00bb691,427,429&#8243; image_count=\u00bb3&#8243; load_more=\u00bbon\u00bb load_more_text=\u00bbCargar M\u00e1s\u00bb show_pagination=\u00bboff\u00bb image_zoom=\u00bbon\u00bb overlay=\u00bbon\u00bb on_click=\u00bblightbox\u00bb lightbox_title=\u00bboff\u00bb lightbox_caption=\u00bboff\u00bb hover_overlay_color=\u00bbrgba(28,55,101,0.71)\u00bb hover_icon=\u00bb&#x4c;||divi||400&#8243; hover_icon_color=\u00bb#f79839&#8243; hover_icon_width=\u00bb35px\u00bb effect_opacity=\u00bbon\u00bb layout_gap_tablet=\u00bb20px\u00bb layout_gap_phone=\u00bb10px\u00bb layout_gap_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbGALINDOFONT|600|||||||\u00bb title_text_color=\u00bb#FFCB58&#8243; title_font_size=\u00bb17px\u00bb caption_font=\u00bbGALINDOFONT||||||||\u00bb caption_font_size=\u00bb13px\u00bb caption_line_height=\u00bb1.3em\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#F6F1EC\u00bb button_bg_color=\u00bb#f79839&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#f4c538&#8243; button_border_radius=\u00bb50px\u00bb button_font=\u00bbGALINDOFONT||||||||\u00bb button_use_icon=\u00bboff\u00bb button_alignment=\u00bbcenter\u00bb button_custom_margin=\u00bb||||false|false\u00bb button_custom_padding=\u00bb7px|37px|7px|37px|true|true\u00bb image_icon_custom_margin=\u00bb||0px||false|false\u00bb image_icon_custom_padding=\u00bb||0px||false|false\u00bb filter_custom_padding_tablet=\u00bb||10px||false|false\u00bb filter_custom_padding_phone=\u00bb|5px|10px|5px|false|true\u00bb filter_custom_padding_last_edited=\u00bbon|phone\u00bb max_width=\u00bb709px\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|desktop\u00bb module_alignment=\u00bbcenter\u00bb animation_style=\u00bbfade\u00bb animation_duration=\u00bb500ms\u00bb title_font_size_tablet=\u00bb\u00bb title_font_size_phone=\u00bb18px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb caption_text_align_phone=\u00bbcenter\u00bb caption_text_align_last_edited=\u00bboff|phone\u00bb caption_font_size_tablet=\u00bb15px\u00bb caption_font_size_phone=\u00bb13px\u00bb caption_font_size_last_edited=\u00bbon|phone\u00bb filter_font_size_tablet=\u00bb20px\u00bb filter_font_size_phone=\u00bb17px\u00bb filter_font_size_last_edited=\u00bbon|phone\u00bb border_radii_image=\u00bbon|10px|10px|10px|10px\u00bb border_color_all_image=\u00bbRGBA(255,255,255,0)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb filter_text_color__hover_enabled=\u00bbon|hover\u00bb filter_text_color__hover=\u00bb#764699&#8243; border_color_all_image__hover_enabled=\u00bbon|desktop\u00bb border_color_all_image__hover=\u00bb#F6F1EC\u00bb button_border_color__hover_enabled=\u00bbon|desktop\u00bb button_border_color__hover=\u00bb#f2b437&#8243; button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#F6F1EC\u00bb button_bg_color__hover_enabled=\u00bbon|desktop\u00bb button_bg_color__hover=\u00bb#ffb73a\u00bb button_bg_enable_color__hover=\u00bbon\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/dondivi_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text module_class=\u00bbpa-toggle-text\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Las Torres del Poeta es un proyecto de edificio conformado por 4 torres dando un total de 106,431 metros cuadrados construidos, lo que lo convierte en la edificaci\u00f3n m\u00e1s grande del sector privado de Bolivia. Asimismo, dos de sus torres son el segundo y tercer edificio m\u00e1s alto del pa\u00eds, la m\u00e1s alta teniendo una altura de 178 metros.<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>Las torres fueron acertadamente nombradas en conmemoraci\u00f3n a poetas con gran renombre en la historia <span><a tabindex=\"-1\"><\/a><\/span>de Bolivia.<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<p>&nbsp;<\/p>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">&#8211; Torre \u00abA\u00bb: Jaime S\u00e1enz<\/div>\n<div dir=\"auto\">&#8211; Torre \u00abB\u00bb: Adela Zamudio<\/div>\n<div dir=\"auto\">&#8211; Torre \u00abC\u00bb: Mar\u00eda Josefa Mujia<\/div>\n<div dir=\"auto\">\n<p>&#8211; Torre \u00abD\u00bb: Franz Tamayo<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<p>&nbsp;<\/p>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>En cuanto al comportamiento estructural, es importante entender que, en edificios altos, las acciones horizontales de viento y sismo son los esfuerzos m\u00e1s grandes que debe resistir la estructura.<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<p>&nbsp;<\/p>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>La acci\u00f3n del viento depende de las superficies y formas del edificio, as\u00ed como su altura y entorno urbano donde se encuentre. Por su parte, las acciones s\u00edsmicas son m\u00e1s complejas, ya que su valor no solo depende de la aceleraci\u00f3n del suelo para un determinado periodo de retorno, sino tambi\u00e9n de las caracter\u00edsticas de la estructura resistente, de su masa, rigidez y amortiguamiento, que determinan los modos naturales de vibraci\u00f3n y los periodos. Ambas cargas son eminentemente aleatorias y, por tanto, de un tratamiento complejo en el estudio de las estructuras.<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<p>&nbsp;<\/p>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\n<p>Nuestro trabajo consisti\u00f3 en la verificaci\u00f3n de la capacidad sismorresistente de las torres. El dise\u00f1o que hicimos permiti\u00f3 implementar algunas mejoras a la estructura que, aunque fueron econ\u00f3micas, redundaron en un incremento significativo de esta capacidad sismorresistente.<\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<p>&nbsp;<\/p>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<ul>\n<li><span>Fecha: 2012 \u2013 La Paz, Bolivia<\/span><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; module_id=\u00bbprogramas\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttp:\/\/galindoingenieria.com\/wp-content\/uploads\/2023\/04\/6-1.jpg\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAVENIR REAL|800|||||||\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb54px\u00bb text_orientation=\u00bbcenter\u00bb text_font_last_edited=\u00bboff|desktop\u00bb text_font_size_tablet=\u00bb\u00bb text_font_size_phone=\u00bb29px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>Desarrollo de Programas Estructurales<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT|800|||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb54px\u00bb text_line_height=\u00bb1.2em\u00bb text_orientation=\u00bbcenter\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb\u00bb width_last_edited=\u00bbon|phone\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb54px\u00bb text_font_size_phone=\u00bb34px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>GALGO<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][dondivi_gallery gallery_ids=\u00bb433,432&#8243; image_count=\u00bb3&#8243; load_more=\u00bbon\u00bb load_more_text=\u00bbCargar M\u00e1s\u00bb show_pagination=\u00bboff\u00bb image_zoom=\u00bbon\u00bb overlay=\u00bbon\u00bb on_click=\u00bblightbox\u00bb lightbox_title=\u00bboff\u00bb lightbox_caption=\u00bboff\u00bb hover_overlay_color=\u00bbrgba(28,55,101,0.71)\u00bb hover_icon=\u00bb&#x4c;||divi||400&#8243; hover_icon_color=\u00bb#f79839&#8243; hover_icon_width=\u00bb35px\u00bb effect_opacity=\u00bbon\u00bb layout_gap_tablet=\u00bb20px\u00bb layout_gap_phone=\u00bb10px\u00bb layout_gap_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbGALINDOFONT|600|||||||\u00bb title_text_color=\u00bb#FFCB58&#8243; title_font_size=\u00bb17px\u00bb caption_font=\u00bbGALINDOFONT||||||||\u00bb caption_font_size=\u00bb13px\u00bb caption_line_height=\u00bb1.3em\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#F6F1EC\u00bb button_bg_color=\u00bb#f79839&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#f4c538&#8243; button_border_radius=\u00bb50px\u00bb button_font=\u00bbGALINDOFONT||||||||\u00bb button_use_icon=\u00bboff\u00bb button_alignment=\u00bbcenter\u00bb button_custom_margin=\u00bb||||false|false\u00bb button_custom_padding=\u00bb7px|37px|7px|37px|true|true\u00bb image_icon_custom_margin=\u00bb||0px||false|false\u00bb image_icon_custom_padding=\u00bb||0px||false|false\u00bb filter_custom_padding_tablet=\u00bb||10px||false|false\u00bb filter_custom_padding_phone=\u00bb|5px|10px|5px|false|true\u00bb filter_custom_padding_last_edited=\u00bbon|phone\u00bb max_width=\u00bb709px\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|desktop\u00bb module_alignment=\u00bbcenter\u00bb animation_style=\u00bbfade\u00bb animation_duration=\u00bb500ms\u00bb title_font_size_tablet=\u00bb\u00bb title_font_size_phone=\u00bb18px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb caption_text_align_phone=\u00bbcenter\u00bb caption_text_align_last_edited=\u00bboff|phone\u00bb caption_font_size_tablet=\u00bb15px\u00bb caption_font_size_phone=\u00bb13px\u00bb caption_font_size_last_edited=\u00bbon|phone\u00bb filter_font_size_tablet=\u00bb20px\u00bb filter_font_size_phone=\u00bb17px\u00bb filter_font_size_last_edited=\u00bbon|phone\u00bb border_radii_image=\u00bbon|10px|10px|10px|10px\u00bb border_color_all_image=\u00bbRGBA(255,255,255,0)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb filter_text_color__hover_enabled=\u00bbon|hover\u00bb filter_text_color__hover=\u00bb#764699&#8243; border_color_all_image__hover_enabled=\u00bbon|desktop\u00bb border_color_all_image__hover=\u00bb#F6F1EC\u00bb button_border_color__hover_enabled=\u00bbon|desktop\u00bb button_border_color__hover=\u00bb#f2b437&#8243; button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#F6F1EC\u00bb button_bg_color__hover_enabled=\u00bbon|desktop\u00bb button_bg_color__hover=\u00bb#ffb73a\u00bb button_bg_enable_color__hover=\u00bbon\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/dondivi_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text module_class=\u00bbpa-toggle-text\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>\u00a0GALGO (Galindo General Optimization) es un programa de optimizaci\u00f3n estructural general que interacciona con nuestros otros programas de an\u00e1lisis estructural y tiene distintos algoritmos de b\u00fasqueda de la soluci\u00f3n \u00f3ptima, permiti\u00e9ndonos ofrecerles ahorros importantes a nuestros clientes. El programa esta desarrollado en PASCAL con objetos.<\/span><\/p>\n<p><span><\/span><\/p>\n<ul>\n<li><span>Fecha: 1984 &#8211; Presente<\/span><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb17px||21px|||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_divider color=\u00bb#E09900&#8243; divider_weight=\u00bb4px\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT|800|||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb54px\u00bb text_line_height=\u00bb1.2em\u00bb text_orientation=\u00bbcenter\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb\u00bb width_last_edited=\u00bbon|phone\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb54px\u00bb text_font_size_phone=\u00bb34px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>FEM Lab<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][dondivi_gallery gallery_ids=\u00bb436,435&#8243; image_count=\u00bb3&#8243; load_more=\u00bbon\u00bb load_more_text=\u00bbCargar M\u00e1s\u00bb show_pagination=\u00bboff\u00bb image_zoom=\u00bbon\u00bb overlay=\u00bbon\u00bb on_click=\u00bblightbox\u00bb lightbox_title=\u00bboff\u00bb lightbox_caption=\u00bboff\u00bb hover_overlay_color=\u00bbrgba(28,55,101,0.71)\u00bb hover_icon=\u00bb&#x4c;||divi||400&#8243; hover_icon_color=\u00bb#f79839&#8243; hover_icon_width=\u00bb35px\u00bb effect_opacity=\u00bbon\u00bb layout_gap_tablet=\u00bb20px\u00bb layout_gap_phone=\u00bb10px\u00bb layout_gap_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbGALINDOFONT|600|||||||\u00bb title_text_color=\u00bb#FFCB58&#8243; title_font_size=\u00bb17px\u00bb caption_font=\u00bbGALINDOFONT||||||||\u00bb caption_font_size=\u00bb13px\u00bb caption_line_height=\u00bb1.3em\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#F6F1EC\u00bb button_bg_color=\u00bb#f79839&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#f4c538&#8243; button_border_radius=\u00bb50px\u00bb button_font=\u00bbGALINDOFONT||||||||\u00bb button_use_icon=\u00bboff\u00bb button_alignment=\u00bbcenter\u00bb button_custom_margin=\u00bb||||false|false\u00bb button_custom_padding=\u00bb7px|37px|7px|37px|true|true\u00bb image_icon_custom_margin=\u00bb||0px||false|false\u00bb image_icon_custom_padding=\u00bb||0px||false|false\u00bb filter_custom_padding_tablet=\u00bb||10px||false|false\u00bb filter_custom_padding_phone=\u00bb|5px|10px|5px|false|true\u00bb filter_custom_padding_last_edited=\u00bbon|phone\u00bb max_width=\u00bb709px\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|desktop\u00bb module_alignment=\u00bbcenter\u00bb animation_style=\u00bbfade\u00bb animation_duration=\u00bb500ms\u00bb title_font_size_tablet=\u00bb\u00bb title_font_size_phone=\u00bb18px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb caption_text_align_phone=\u00bbcenter\u00bb caption_text_align_last_edited=\u00bboff|phone\u00bb caption_font_size_tablet=\u00bb15px\u00bb caption_font_size_phone=\u00bb13px\u00bb caption_font_size_last_edited=\u00bbon|phone\u00bb filter_font_size_tablet=\u00bb20px\u00bb filter_font_size_phone=\u00bb17px\u00bb filter_font_size_last_edited=\u00bbon|phone\u00bb border_radii_image=\u00bbon|10px|10px|10px|10px\u00bb border_color_all_image=\u00bbRGBA(255,255,255,0)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb filter_text_color__hover_enabled=\u00bbon|hover\u00bb filter_text_color__hover=\u00bb#764699&#8243; border_color_all_image__hover_enabled=\u00bbon|desktop\u00bb border_color_all_image__hover=\u00bb#F6F1EC\u00bb button_border_color__hover_enabled=\u00bbon|desktop\u00bb button_border_color__hover=\u00bb#f2b437&#8243; button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#F6F1EC\u00bb button_bg_color__hover_enabled=\u00bbon|desktop\u00bb button_bg_color__hover=\u00bb#ffb73a\u00bb button_bg_enable_color__hover=\u00bbon\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/dondivi_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text module_class=\u00bbpa-toggle-text\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>FEM Lab (Finite Elements Method Laboratoy) es nuestro programa mas importante desarrollado inicialmente en la Universidad Polit\u00e9cnica de Catalu\u00f1a en el Doctorado de Mario Galindo Queralt y que sigue en desarrollo permanente hasta la fecha. Este programa contempla an\u00e1lisis no lineal tanto geom\u00e9trico como mec\u00e1nico por elementos finitos considerando cargas est\u00e1ticas, din\u00e1micas y t\u00e9rmicas. El programa permite tener en cuenta la interacci\u00f3n entre varios s\u00f3lidos y fluidos simult\u00e1neamente con procesamiento paralelo. Su desarrollo inicio en Fortran, pero desde 1992 fue rehecho en C++ y se lo ha vinculado a otro programa de pre y post proceso.<\/span><\/p>\n<ul>\n<li><span>Fechas: 1986 &#8211; Presente<\/span><\/li>\n<\/ul>\n<p><span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb17px||21px|||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_divider color=\u00bb#E09900&#8243; divider_weight=\u00bb4px\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT|800|||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb54px\u00bb text_line_height=\u00bb1.2em\u00bb text_orientation=\u00bbcenter\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb\u00bb width_last_edited=\u00bbon|phone\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb54px\u00bb text_font_size_phone=\u00bb34px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>CID<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][dondivi_gallery gallery_ids=\u00bb440,438&#8243; image_count=\u00bb3&#8243; load_more=\u00bbon\u00bb load_more_text=\u00bbCargar M\u00e1s\u00bb show_pagination=\u00bboff\u00bb image_zoom=\u00bbon\u00bb overlay=\u00bbon\u00bb on_click=\u00bblightbox\u00bb lightbox_title=\u00bboff\u00bb lightbox_caption=\u00bboff\u00bb hover_overlay_color=\u00bbrgba(28,55,101,0.71)\u00bb hover_icon=\u00bb&#x4c;||divi||400&#8243; hover_icon_color=\u00bb#f79839&#8243; hover_icon_width=\u00bb35px\u00bb effect_opacity=\u00bbon\u00bb layout_gap_tablet=\u00bb20px\u00bb layout_gap_phone=\u00bb10px\u00bb layout_gap_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbGALINDOFONT|600|||||||\u00bb title_text_color=\u00bb#FFCB58&#8243; title_font_size=\u00bb17px\u00bb caption_font=\u00bbGALINDOFONT||||||||\u00bb caption_font_size=\u00bb13px\u00bb caption_line_height=\u00bb1.3em\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#F6F1EC\u00bb button_bg_color=\u00bb#f79839&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#f4c538&#8243; button_border_radius=\u00bb50px\u00bb button_font=\u00bbGALINDOFONT||||||||\u00bb button_use_icon=\u00bboff\u00bb button_alignment=\u00bbcenter\u00bb button_custom_margin=\u00bb||||false|false\u00bb button_custom_padding=\u00bb7px|37px|7px|37px|true|true\u00bb image_icon_custom_margin=\u00bb||0px||false|false\u00bb image_icon_custom_padding=\u00bb||0px||false|false\u00bb filter_custom_padding_tablet=\u00bb||10px||false|false\u00bb filter_custom_padding_phone=\u00bb|5px|10px|5px|false|true\u00bb filter_custom_padding_last_edited=\u00bbon|phone\u00bb max_width=\u00bb709px\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|desktop\u00bb module_alignment=\u00bbcenter\u00bb animation_style=\u00bbfade\u00bb animation_duration=\u00bb500ms\u00bb title_font_size_tablet=\u00bb\u00bb title_font_size_phone=\u00bb18px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb caption_text_align_phone=\u00bbcenter\u00bb caption_text_align_last_edited=\u00bboff|phone\u00bb caption_font_size_tablet=\u00bb15px\u00bb caption_font_size_phone=\u00bb13px\u00bb caption_font_size_last_edited=\u00bbon|phone\u00bb filter_font_size_tablet=\u00bb20px\u00bb filter_font_size_phone=\u00bb17px\u00bb filter_font_size_last_edited=\u00bbon|phone\u00bb border_radii_image=\u00bbon|10px|10px|10px|10px\u00bb border_color_all_image=\u00bbRGBA(255,255,255,0)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb filter_text_color__hover_enabled=\u00bbon|hover\u00bb filter_text_color__hover=\u00bb#764699&#8243; border_color_all_image__hover_enabled=\u00bbon|desktop\u00bb border_color_all_image__hover=\u00bb#F6F1EC\u00bb button_border_color__hover_enabled=\u00bbon|desktop\u00bb button_border_color__hover=\u00bb#f2b437&#8243; button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#F6F1EC\u00bb button_bg_color__hover_enabled=\u00bbon|desktop\u00bb button_bg_color__hover=\u00bb#ffb73a\u00bb button_bg_enable_color__hover=\u00bbon\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/dondivi_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text module_class=\u00bbpa-toggle-text\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>CID (Concrete Interaction Diagram) es un programa capaz de dimensionar una secci\u00f3n de hormig\u00f3n amado con cualquier forma, con armado asim\u00e9trico y acero de pretensado. Este programa fue \u00edntegramente desarrollado e implementado en el lenguaje de programaci\u00f3n Python.<\/span><\/p>\n<ul>\n<li><span>Fecha: 2020 \u2013 Presente<\/span><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT|800|||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb54px\u00bb text_line_height=\u00bb1.2em\u00bb text_orientation=\u00bbcenter\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb\u00bb width_last_edited=\u00bbon|phone\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb54px\u00bb text_font_size_phone=\u00bb34px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>Viguetas SOBOPRET<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][dondivi_gallery gallery_ids=\u00bb504,505&#8243; image_count=\u00bb2&#8243; load_more=\u00bbon\u00bb load_more_text=\u00bbCargar M\u00e1s\u00bb show_pagination=\u00bboff\u00bb image_zoom=\u00bbon\u00bb overlay=\u00bbon\u00bb on_click=\u00bblightbox\u00bb lightbox_title=\u00bboff\u00bb lightbox_caption=\u00bboff\u00bb hover_overlay_color=\u00bbrgba(28,55,101,0.71)\u00bb hover_icon=\u00bb&#x4c;||divi||400&#8243; hover_icon_color=\u00bb#f79839&#8243; hover_icon_width=\u00bb35px\u00bb effect_opacity=\u00bbon\u00bb layout_gap_tablet=\u00bb20px\u00bb layout_gap_phone=\u00bb10px\u00bb layout_gap_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbGALINDOFONT|600|||||||\u00bb title_text_color=\u00bb#FFCB58&#8243; title_font_size=\u00bb17px\u00bb caption_font=\u00bbGALINDOFONT||||||||\u00bb caption_font_size=\u00bb13px\u00bb caption_line_height=\u00bb1.3em\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#F6F1EC\u00bb button_bg_color=\u00bb#f79839&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#f4c538&#8243; button_border_radius=\u00bb50px\u00bb button_font=\u00bbGALINDOFONT||||||||\u00bb button_use_icon=\u00bboff\u00bb button_alignment=\u00bbcenter\u00bb button_custom_margin=\u00bb||||false|false\u00bb button_custom_padding=\u00bb7px|37px|7px|37px|true|true\u00bb image_icon_custom_margin=\u00bb||0px||false|false\u00bb image_icon_custom_padding=\u00bb||0px||false|false\u00bb filter_custom_padding_tablet=\u00bb||10px||false|false\u00bb filter_custom_padding_phone=\u00bb|5px|10px|5px|false|true\u00bb filter_custom_padding_last_edited=\u00bbon|phone\u00bb max_width=\u00bb709px\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|desktop\u00bb module_alignment=\u00bbcenter\u00bb animation_style=\u00bbfade\u00bb animation_duration=\u00bb500ms\u00bb title_font_size_tablet=\u00bb\u00bb title_font_size_phone=\u00bb18px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb caption_text_align_phone=\u00bbcenter\u00bb caption_text_align_last_edited=\u00bboff|phone\u00bb caption_font_size_tablet=\u00bb15px\u00bb caption_font_size_phone=\u00bb13px\u00bb caption_font_size_last_edited=\u00bbon|phone\u00bb filter_font_size_tablet=\u00bb20px\u00bb filter_font_size_phone=\u00bb17px\u00bb filter_font_size_last_edited=\u00bbon|phone\u00bb border_radii_image=\u00bbon|10px|10px|10px|10px\u00bb border_color_all_image=\u00bbRGBA(255,255,255,0)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb filter_text_color__hover_enabled=\u00bbon|hover\u00bb filter_text_color__hover=\u00bb#764699&#8243; border_color_all_image__hover_enabled=\u00bbon|desktop\u00bb border_color_all_image__hover=\u00bb#F6F1EC\u00bb button_border_color__hover_enabled=\u00bbon|desktop\u00bb button_border_color__hover=\u00bb#f2b437&#8243; button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#F6F1EC\u00bb button_bg_color__hover_enabled=\u00bbon|desktop\u00bb button_bg_color__hover=\u00bb#ffb73a\u00bb button_bg_enable_color__hover=\u00bbon\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/dondivi_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text module_class=\u00bbpa-toggle-text\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbGALINDOFONT||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb17px\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p>SOBOPRET dependiente de SOBOCE S.A. nos contrat\u00f3 el a\u00f1o 2022 para verificar y dise\u00f1ar sus viguetas pretensadas. En este proyecto se hizo el estudio y la verificaci\u00f3n de todos los tipos de losas, para vigueta simple y doble, con los espaciamientos de 30, 40, 50, 60, 70 y 80 cent\u00edmetros. El resultado es que, modificando algunas viguetas, hemos comprobado que las mismas se pueden emplear hasta en una luz de 9.70 metros en estructuras de viviendas con las seguridades dadas en las normas bolivianas. Este proyecto fue realizado utilizando nuestro programa CID con el cual hemos calculado los diagramas de interacci\u00f3n de rotura, fisuraci\u00f3n, no tracci\u00f3n y servicio.<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; module_id=\u00bbverificacion\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttp:\/\/galindoingenieria.com\/wp-content\/uploads\/2023\/04\/5-1.jpg\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAVENIR REAL|800|||||||\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb54px\u00bb text_orientation=\u00bbcenter\u00bb text_font_last_edited=\u00bboff|desktop\u00bb text_font_size_tablet=\u00bb\u00bb text_font_size_phone=\u00bb29px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>Dise\u00f1o y Verificaci\u00f3n<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_button button_url=\u00bb#footer\u00bb button_text=\u00bbCont\u00e1ctanos\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#4bc3a8&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb24px\u00bb button_font=\u00bbAVENIR REAL||||||||\u00bb positioning=\u00bbfixed\u00bb position_origin_f=\u00bbbottom_right\u00bb vertical_offset=\u00bb32px\u00bb horizontal_offset=\u00bb32px\u00bb z_index=\u00bb42&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#002f66&#8243; custom_padding=\u00bb14px||0px|||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px||0px|||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_button button_url=\u00bb#main\u00bb button_text=\u00bb.\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bbRGBA(255,255,255,0)\u00bb button_bg_color=\u00bb#06367f\u00bb button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#0C71C3&#8243; button_border_radius=\u00bb100px\u00bb button_font=\u00bbAvenir||||||||\u00bb button_icon=\u00bb&#xf0aa;||fa||900&#8243; button_icon_color=\u00bb#FFFFFF\u00bb button_on_hover=\u00bboff\u00bb positioning=\u00bbfixed\u00bb position_origin_f=\u00bbbottom_right\u00bb vertical_offset=\u00bb88px\u00bb horizontal_offset=\u00bb30px\u00bb z_index=\u00bb43&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ProyectosA continuaci\u00f3n, se presentan una selecci\u00f3n peque\u00f1a de nuestros proyectos que han tenido un detalle at\u00edpico, ya sea por su trascendencia arquitect\u00f3nica, una dificultad estructural o una dificultad de c\u00e1lculo. Haga click en la categor\u00eda que desee ver.Hormig\u00f3n PretensadoHormig\u00f3n\u00a0 ArmadoEstructuras Met\u00e1licasReparaci\u00f3n de estructuras y patolog\u00edaDesarrollo de Programas EstructuralesDise\u00f1o y Verificaci\u00f3n[wdcl_image_carousel is_variable_width=\u00bbon\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][wdcl_image_carousel_child [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-406160","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/galindoingenieria.com\/eng\/wp-json\/wp\/v2\/pages\/406160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galindoingenieria.com\/eng\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/galindoingenieria.com\/eng\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/galindoingenieria.com\/eng\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/galindoingenieria.com\/eng\/wp-json\/wp\/v2\/comments?post=406160"}],"version-history":[{"count":3,"href":"https:\/\/galindoingenieria.com\/eng\/wp-json\/wp\/v2\/pages\/406160\/revisions"}],"predecessor-version":[{"id":406163,"href":"https:\/\/galindoingenieria.com\/eng\/wp-json\/wp\/v2\/pages\/406160\/revisions\/406163"}],"wp:attachment":[{"href":"https:\/\/galindoingenieria.com\/eng\/wp-json\/wp\/v2\/media?parent=406160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}